{"text_format":"1","workbook":"xlsx","n_sheets":15,"sheets":["Administration","Calculator","Sheet2","Calculation Worksheet Page 1","Calculation Worksheet Page 2","NAF","HAP Contract","Lease","Occupancy Continuation Form 1","Occupancy Continuation Form 2","Payment Notification Approval","Rent Reasonableness","Notification of Annual Review","Contract Amendment","VAWA Lease Addendum"],"not_rendered":{"charts":0,"images":22,"macros":1,"external_links":0,"defined_names":13,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Administration","index":0,"n_rows":503,"n_cols":16,"rows_kept":503,"cut":false,"hidden":false,"merged":[[117,2,117,4],[119,5,119,6],[119,8,119,12],[121,2,121,4],[169,3,169,6],[168,6,168,7],[141,2,141,3],[146,3,146,4],[165,6,165,7],[150,10,151,11],[148,3,148,4],[148,9,148,10],[148,6,148,7],[131,3,131,5],[167,2,167,4],[168,2,168,4],[151,8,151,9],[145,0,145,2],[138,2,138,3],[147,3,147,4],[106,8,106,9],[100,6,100,7],[116,2,116,4],[100,2,100,3],[101,2,101,3],[103,2,103,3],[102,6,102,7],[103,6,103,7],[109,2,109,4],[110,2,110,4],[115,8,115,9],[115,4,115,6],[107,8,107,9],[306,8,306,9],[236,10,236,11],[232,10,232,11],[143,2,143,5],[146,0,146,2],[166,2,166,4],[172,0,172,12],[166,6,166,7],[167,6,167,7],[159,2,163,9],[237,4,237,8],[213,3,214,9],[199,2,199,4],[175,3,175,6],[280,10,283,12],[264,10,264,11],[259,1,259,8],[280,6,283,6],[280,7,283,7],[280,8,283,9],[271,0,271,2],[272,0,272,2],[255,0,255,3],[293,4,293,12],[307,2,307,4],[176,3,176,7],[101,6,101,7],[310,0,310,1],[309,2,309,4],[106,0,106,1],[102,2,102,3],[310,2,310,4],[309,5,309,7],[310,5,310,7],[189,3,189,8],[204,3,204,8],[286,1,286,4],[308,0,308,1],[306,0,306,1],[195,0,195,12],[198,2,198,3],[206,2,206,6],[197,2,197,6],[196,2,196,12],[307,5,307,7],[284,8,284,9],[280,1,283,4],[280,5,283,5],[288,1,288,4],[183,3,183,4],[205,2,205,12],[185,3,185,4],[304,2,304,4],[294,0,294,12],[287,8,287,9],[288,8,288,9],[249,0,249,3],[285,10,285,12],[278,11,278,12],[209,3,209,5],[256,0,256,3],[212,0,212,2],[237,10,237,11],[284,10,284,12],[266,5,266,6],[278,3,278,4],[278,7,278,8],[276,0,276,12],[262,10,262,11],[263,10,263,11],[284,1,284,4],[261,10,261,11],[1,7,1,8],[7,5,7,7],[8,2,8,5],[13,2,13,3],[9,2,9,8],[46,8,46,12],[47,8,47,12],[43,9,43,10],[56,8,56,12],[52,9,52,10],[15,2,15,3],[21,2,21,8],[36,8,36,12],[422,3,422,4],[422,7,422,8],[420,5,420,6],[421,5,421,6],[2,0,2,8],[3,3,3,4],[6,0,6,8],[7,1,7,4],[4,2,4,4],[80,2,80,4],[81,0,81,1],[88,0,89,3],[91,4,91,5],[68,8,68,12],[73,9,73,10],[57,8,57,12],[64,9,64,10],[85,0,86,3],[77,0,77,12],[79,2,79,3],[76,0,76,12],[67,8,67,12],[21,0,21,1],[178,1,178,5],[407,7,414,8],[416,9,416,10],[415,7,415,8],[424,9,424,10],[401,7,406,8],[421,7,421,8],[417,5,417,6],[419,7,419,8],[420,7,420,8],[418,7,418,8],[415,5,415,6],[415,9,415,10],[416,5,416,6],[491,3,491,4],[417,9,417,10],[420,9,420,10],[421,9,421,10],[484,3,484,4],[425,7,425,8],[460,2,460,4],[455,3,455,4],[459,2,459,6],[470,0,470,12],[451,0,451,12],[461,0,461,3],[461,4,461,6],[427,1,427,2],[447,2,447,5],[425,3,425,4],[425,5,425,6],[431,6,431,7],[447,8,447,10],[457,2,457,5],[453,1,453,2],[489,2,489,3],[459,7,459,12],[424,3,424,4],[391,9,391,10],[396,11,396,12],[474,2,474,3],[339,2,339,7],[338,2,338,7],[337,2,337,7],[329,2,329,9],[330,2,330,9],[335,6,335,7],[344,2,344,7],[392,11,395,12],[400,7,400,8],[397,11,397,12],[396,9,396,10],[397,9,397,10],[417,7,417,8],[420,3,420,4],[421,3,421,4],[401,3,406,4],[401,5,406,6],[416,7,416,8],[401,9,406,10],[407,3,414,4],[407,5,414,6],[476,2,476,3],[480,2,480,5],[482,2,482,6],[424,5,424,6],[422,9,422,10],[407,0,407,2],[422,5,422,6],[418,9,418,10],[419,9,419,10],[418,5,418,6],[423,9,423,10],[423,7,423,8],[424,7,424,8],[407,9,414,10],[409,0,409,2],[411,0,411,2],[423,5,423,6],[423,3,423,4],[419,5,419,6],[472,2,472,4],[465,0,465,3],[466,0,466,3],[464,0,464,3],[425,9,425,10],[32,15,32,17],[17,3,17,5],[136,0,136,6],[123,2,123,5],[129,3,129,6],[165,2,165,4],[145,3,145,4],[140,2,140,5],[148,0,148,2],[132,3,132,4],[133,3,133,4],[135,3,135,4],[137,2,137,3],[134,3,134,6],[130,3,130,5],[142,2,142,3],[96,6,96,7],[139,2,139,3],[128,2,128,11],[147,0,147,2],[112,0,112,12],[99,6,99,7],[80,0,80,1],[86,4,86,5],[260,1,260,8],[231,10,231,11],[231,4,231,8],[232,4,232,8],[250,0,250,3],[236,0,236,2],[236,4,236,8],[261,1,261,8],[260,10,260,11],[229,0,231,2],[314,11,314,12],[306,2,306,4],[309,8,309,9],[310,8,310,9],[16,0,16,2],[305,0,305,1],[304,0,304,1],[305,5,305,7],[304,5,304,7],[22,1,22,3],[25,0,25,1],[27,2,27,3],[33,0,33,12],[29,3,29,4],[20,1,20,8],[26,3,26,4],[32,0,32,12],[34,0,34,12],[35,8,35,12],[220,1,220,3],[237,0,237,2],[210,5,210,8],[263,1,263,8],[264,1,264,8],[345,2,345,7],[332,2,332,7],[333,2,333,7],[327,5,327,6],[326,2,326,4],[308,2,308,4],[327,2,327,4],[308,5,308,7],[98,6,98,7],[262,1,262,8],[326,7,326,9],[314,2,314,6],[318,0,318,12],[328,7,328,9],[328,5,328,6],[327,7,327,9],[316,1,316,7],[184,3,184,4],[306,5,306,7],[305,8,305,9],[286,10,286,12],[289,10,289,12],[290,10,290,12],[288,10,288,12],[357,0,357,1],[357,2,357,4],[359,0,359,1],[377,2,377,3],[377,0,377,1],[379,0,379,1],[366,1,366,2],[363,0,363,12],[259,10,259,11],[303,5,303,7],[308,8,308,9],[307,8,307,9],[285,8,285,9],[289,1,289,4],[290,1,290,4],[289,8,289,9],[290,8,290,9],[285,1,285,4],[309,0,309,1],[286,8,286,9],[287,1,287,4],[292,4,292,12],[287,10,287,12],[305,2,305,4],[0,4,0,8],[1,5,1,6],[1,2,1,4],[396,5,396,6],[396,7,396,8],[353,2,353,7],[354,2,354,7],[392,7,395,8],[328,2,328,4],[326,5,326,6],[304,8,304,9],[97,6,97,7],[0,0,0,2],[10,1,10,3],[13,0,13,1],[14,0,14,1],[14,2,14,3],[16,3,16,4],[28,2,28,5],[19,0,19,8],[25,2,25,3],[8,0,8,1],[15,0,15,1],[391,1,391,2],[400,9,400,10],[500,2,500,5],[122,2,122,5],[372,3,372,7],[478,2,478,12],[498,0,498,12],[381,4,381,10],[383,4,383,5],[416,0,416,2],[413,0,413,2],[415,0,415,2],[382,4,382,9],[385,1,385,5],[392,9,395,10],[397,5,397,6],[398,5,399,6],[415,3,415,4],[398,0,399,2],[400,0,400,2],[401,0,406,2],[307,0,307,1],[379,3,379,4],[348,2,348,3],[153,0,153,2],[495,0,495,12],[488,2,488,9],[377,5,377,6],[374,5,375,12],[391,3,391,4],[391,5,391,6],[391,7,391,8],[418,3,418,4],[419,3,419,4],[392,5,395,6],[392,3,395,4],[417,3,417,4],[416,3,416,4],[400,3,400,4],[396,3,396,4],[386,1,386,5],[390,0,390,12],[400,5,400,6],[397,7,397,8],[398,9,399,10],[398,7,399,8],[486,3,486,7],[397,3,397,4],[398,3,399,4]]}
["Fill in the highlighted areas",null,null,null,"Pre-populated fields will be highlighted in light gray"]
["Version 2.1",null,"TRA Tenant Workbook",null,null,"Todays Date:",null,{"$f":"TEXT(TODAY(), \"dddd\") &\", \" & TEXT(TODAY(), \"mm/dd/yyyy\")","v":"Monday, 04/01/2024"},null,null,null,null,null,null,"Clicking \"Clear All Data\" will erase all manually entered data in the administration tab"]
["Grant Information"]
["Federal Grant I.D./HUD Award No.:",null,null,null,null,null,null,null,null,null,null,null,null,null,"Clicking \"Clear All Check Boxes\"  Will uncheck all check boxes in each corresponding section"]
["Contract No.:"]
[null,null,null,null,null,null,null,null,null,null,null,"Information entered into these three sections will carry over to the following areas where appropriate:"]
["Tenant",null,null,null,null,null,null,null,null,null,null,{"$f":"1&\".\"","v":"1."},"Calculation Worksheet Page 1"]
["Name",null,null,null,null,null,null,null,null,null,null,{"$f":"2&\".\"","v":"2."},"Calculation Worksheet Page 2"]
["Street Address",null,null,null,null,null,null,null,null,null,null,{"$f":"3&\".\"","v":"3."},"New Admission Form"]
["Apt #",null,null,null,null,null,null,null,null,null,null,{"$f":"4&\".\"","v":"4."},"HAP Contract"]
["City",null,null,null,null,null,null,null,null,null,null,{"$f":"5&\".\"","v":"5."},"Lease"]
["State",null,null,null,null,null,null,null,null,null,null,{"$f":"6&\".\"","v":"6."},"Occupancy Continuation Form Page 1 "]
["Zip",null,null,null,null,null,null,null,null,null,null,{"$f":"7&\".\"","v":"7."},"Occupancy Continuation Form Page 2"]
["Telephone number",null,null,null,null,null,null,null,null,null,null,{"$f":"8&\".\"","v":"8."},"Payment Notification Approval"]
["Work Number",null,null,null,null,null,null,null,null,null,null,{"$f":"9&\".\"","v":"9."},"Rent Reasonableness "]
["Date of birth",null,null,null,null,null,null,null,null,null,null,{"$f":"10&\".\"","v":"10."},"Notification of Annual Review "]
["Social Security Number",null,null,null,null,null,null,null,null,null,null,{"$f":"11&\".\"","v":"11."},"Contract Amendment "]
["Tenant Account No:",null,null,null,null,null,null,null,null,null,null,{"$f":"12&\".\"","v":"12."},"Vawa Lease Addendum"]
[]
["Landlord"]
["Name"]
["Street Address"]
["City"]
["State"]
["Zip"]
[]
["Owner's Home/Business Phone: "]
["Owner's Business FAX:"]
["Owner's E-Mail:"]
["Owner's State of CT Supplier ID:"]
[]
[]
[" Calculation Worksheet           "]
["Page 1"]
[]
["Household Member #1",null,null,null,null,null,null,null,"Household Member #1 "]
[null,null,null,null,null,null,"Monthly",null,"Weekly Pay"]
["SSDI"]
["SSI",null,null,null,null,null,null,null,null,"Week 1 Pay"]
["TANF",null,null,null,null,null,null,null,null,"Week 2 Pay"]
["Earned Income",null,null,null,null,null,{"$f":"L45+L54","v":0},null,null,"Week 3 Pay"]
["SAGA",null,null,null,null,null,null,null,null,"Week 4 Pay"]
["Unemployment"]
["Child Support",null,null,null,null,null,null,null,null,"Total",null,{"$f":"SUM(L39:L42)","v":0}]
["Alimony",null,null,null,null,null,null,null,null,"Monthly Average",null,{"$f":"FLOOR(L44/4*52/12,1)","v":0}]
["VA Service- Connected Disability Compensation Income"]
["VA Non-Service Connected Disability Pension",null,null,null,null,null,null,null,"Household member #1"]
["Private Disability Insurance Income",null,null,null,null,null,null,null,"Bi-Weekly Pay"]
["Retirement Income from Social Security Income"]
["Pension/ Retirement Income from a former job",null,null,null,null,null,null,null,null,"Bi-Weekly 1st"]
["Worker's Compensation",null,null,null,null,null,null,null,null,"Bi-Weekly 2nd"]
["Other sources of Income"]
[null,null,null,null,null,null,null,null,null,"Total",null,{"$f":"SUM(L50:L51)","v":0}]
[null,null,null,null,null,"Total",{"$f":"SUM(G38:G52)","v":0}," ",null,"Monthly Average",null,{"$f":"FLOOR(L53/2*26/12,1)","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Weekly and Bi-weekly income information will automatically carry over to line 41 EARNED INCOME"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"For household member #1, and Line 62 for household member #2"]
["Household Member #2",null,null,null,null,null,null,null,"Household Member #2"]
[null,null,null,null,null,null,"Monthly",null,"Weekly Pay"]
["SSDI"]
["SSI",null,null,null,null,null,null,null,null,"Week 1 Pay"]
["TANF",null,null,null,null,null,null,null,null,"Week 2 Pay"]
["Earned Income",null,null,null,null,null,{"$f":"L66+L75","v":0},null,null,"Week 3 Pay"]
["SAGA",null,null,null,null,null,null,null,null,"Week 4 Pay"]
["Unemployment"]
["Child Support",null,null,null,null,null,null,null,null,"Total",null,{"$f":"SUM(L60:L63)","v":0}]
["Alimony",null,null,null,null,null,null,null,null,"Monthly Average",null,{"$f":"FLOOR(L65/4*52/12,1)","v":0}]
["VA Service- Connected Disability Compensation Income"]
["VA Non-Service Connected Disability Pension",null,null,null,null,null,null,null,"Household member #2"]
["Private Disability Insurance Income",null,null,null,null,null,null,null,"Bi-Weekly Pay"]
["Retirement Income from Social Security Income"]
["Pension/ Retirement Income from a former job",null,null,null,null,null,null,null,null,"Bi-Weekly 1st"]
["Worker's Compensation",null,null,null,null,null,null,null,null,"Bi-Weekly 2nd"]
["Other sources of Income"]
[null,null,null,null,null,null,null,null,null,"Total",null,{"$f":"SUM(L71:L72)","v":0}]
[null,null,null,null,null,"Total",{"$f":"SUM(G59:G73)","v":0},null,null,"Monthly Average",null,{"$f":"FLOOR(L74/2*26/12,1)","v":0}]
[]
[" Calculation Worksheet           "]
["Page 2"]
[]
["Date"]
["Certificate Number",null,{"$f":"D18","v":0}]
["# of bedrooms"]
["# of Dependents:"]
["# in Household:"]
[]
["For Child Care: (Costs which enable one or both parents to be gainfully employed)"]
[null,null,null,null,null,null,null,"Enter a numerical value only."]
[]
["Non-reimbursed Medical Expenses in excess of 3% of Gross Income:"]
[]
[]
["Non-reimbursed Medical Expenses",null,null,null,null,null,null,"Enter a numerical value only."]
[]
[]
["Allowance for Utilities and Other Services",null,null,null,"Indicate type of allowance",null,"Indicate amount of allowance"]
[]
["Heating:      Natural Gas/Bottle Gas/Oil/Electric"]
["Water Heat: Natural Gas/Bottle Gas/Oil/Electric"]
["Cooking:      Natural Gas/Bottle Gas/Oil/Electric"]
["Other Electric: Lighting, refrigeration, etc."]
[null,"Appliances:   ","Range       "]
[null,"Misc.:         ","Refrigerator"]
[null,null,"Water"]
[null,null,"Trash Collection"]
[]
[]
["Fair Market Rent",null,null,null,null,null,"Family Contribution",null,{"$f":"'Calculation Worksheet Page 2'!H42","v":0}]
["Contract Rent",null,null,null,null,null,"Subsidy Payment",null,{"$f":"'Calculation Worksheet Page 2'!H43","v":0}]
[]
["Preparer's Name:"]
[]
[]
["New Admission Form"]
[]
["1. GRANT INFORMATION"]
["Federal Grant I.D./HUD Award No",null,null,null,{"$f":"D4","v":0},null,null,null,"SID NO.",null,22656]
["Contract No.:",null,{"$f":"C5","v":0},null,null,null,null,null,"Project No.",null,{"$f":"MID(C117, MIN(FIND({0,1,2,3,4,5,6,7,8,9}, C117&\"0123456789\", 8)), 5)","v":{"$error":"#VALUE!"}}]
[]
[]
[1,"   New Admission",null,null,null,"      Re-Certification",null,null,"   Current Participant New Address OR Unit"]
["2. TENANT INFORMATION"]
["Tenant Account No:",null,{"$f":"D18","v":0},null,null,null,"No of bedrooms:",null,{"$f":"C82","v":0}]
["Tenant Name:",null,{"$f":"B8","v":0}]
["Street Address:",null,{"$f":"C9","v":0}]
["City, State and Zip:",null,{"$f":"B10","v":0},null,{"$f":"B11","v":0},null,{"$f":"B12","v":0},null,{"$f":"B13","v":0}]
[null,null,"Apt #",null,"City",null,"State",null,"Zip"]
[]
["3. OWNER INFORMATION"]
["Owner Name:",null,{"$f":"B21","v":0}]
["Owner Street Address:",null,null,{"$f":"C22","v":0}]
["City, State and Zip:",null,null,{"$f":"B23","v":0},null,null,null,{"$f":"B24","v":0},null,{"$f":"B25","v":0}]
[null,null,null,"City",null,null,null,"State",null,"Zip"]
["Owner's Home/Business Phone: ",null,null,{"$f":"D27","v":0}]
["Owner's Business FAX:",null,null,{"$f":"C28","v":0}]
["Owner's E-Mail:",null,null,{"$f":"C29","v":0}]
["Owner's State of CT Supplier ID:",null,null,{"$f":"D30","v":0}]
["Owner's Type of Business (Check Only One):"]
[null,null,"Corporation"]
[null,null,"LLC Corporation"]
[null,null,"LLC Partnership"]
[null,null,"LLC Single member Entity"]
[null,null,"Non-Profit"]
[null,null,"Partnership"]
[null,null,"Individual/Sole Proprietor"]
["4. HAP CONTRACT INFORMATION"]
["Tenant's Payment:",null,null,{"$f":"I107","v":0}]
["Housing Assistance:",null,null,{"$f":"I108","v":0}]
["Contract Rent:",null,null,{"$f":"D146+D147","v":0}]
["Security Deposit:",null,null,null,null,null,"New",null,null,"Previously Paid"]
[]
[]
["Effective Dates of HAP Contract:",null,null,null,"From:",null,"To:",null,"No. of Months:"]
["5. PAYMENT STANDARD COMPLIANCE"]
[" Check Applicable"]
["a.","     Gross rent does not exceed Grant FMR and meets Rent Reasonableness Standards"]
["b.","     Gross rent exceeds Grant FMR but meets Rent Reasonableness Standards"]
[]
["(*By checking b, the local CoC Rental Assistance housing provider verifies that sufficient funds will be available to fulfill the original"]
["grant award obligation with grant award funds.)"]
[]
[]
[]
["COMMENTS:"]
[]
[]
["Submitted By:"]
[null,null,"Name",null,null,null,"Date"]
["Reviewed By:"]
[null,null,"Name",null,null,null,"Date"]
[]
[]
[]
["HAP Contract"]
[]
[]
["Contract Unit Street Address:",null,null,{"$f":"C124&\" \"&Sheet2!J2&\" \"&Administration!C125&\" \"","v":"0  0 "}]
["City, State and Zip:",null,null,{"$f":"E125&\"  \"&G125&\" \"&\" \"&I125","v":"0  0  0"}]
[]
["Family:",{"$f":"C123","v":0}]
[]
["The term of this Contract shall begin on: ",null,null,null,null,{"$f":"F152","v":"00:00:00"}]
["The term of this Contract shall end on: ",null,null,null,null,{"$f":"H152","v":"00:00:00"}]
[]
["Contract rent amount:",null,null,{"$f":"D148","v":0}]
["Family contribution:",null,null,{"$f":"D146","v":0}]
["Housing Assistance: ",null,null,{"$f":"D147","v":0}]
[]
["Security Deposit Amount:"]
[]
["Security Deposit Paid By:"]
[]
["Owner Name:",null,null,{"$f":"C129","v":0}]
[]
[]
[]
["Lease"]
["Owner:",null,{"$f":"C129","v":0}]
["Tenant:",null,{"$f":"C123","v":0}]
["APT #",null,{"$f":"C125","v":0}]
["Street address:",null,{"$f":"C124","v":0}]
["City:",null,{"$f":"E125","v":0}]
["State:",null,{"$f":"G125","v":0}]
["Zip:",null,{"$f":"I125","v":0}]
[]
["Following furniture and appliances:"]
["Owner name:",null,{"$f":"C129","v":0}]
["Tenant name:",null,{"$f":"C123","v":0}]
["Lease start:",null,{"$f":"F152","v":"00:00:00"}]
["Lease ends:",null,{"$f":"H152","v":"00:00:00"}]
["Total number of Months:",null,null,{"$f":"K151","v":0}]
["Security Deposit:   The amount of security deposit paid by",null,null,null,null,{"$f":"D190","v":0}]
["Security Deposit Amount:",null,null,{"$f":"D188","v":0}]
[]
["Use of apartment by:"]
[]
["Utilities:"]
[]
["We will pay the utilities checked with “we” and you will pay the utilities checked "]
["with “you”."]
[]
["Utilities:","       Indicate WE or YOU"]
["General Electricity :"]
["Range:"]
["Hot Water:"]
["Heat:"]
["Cooking Fuel:"]
["Refuse Removal:"]
["Refrigerator:"]
[]
[{"$f":"C129","v":0}]
[]
[null,null,null,null,{"$f":"D130&\" \"&D131&\" \"&H131&\" \"&J131","v":"0 0 0 0"},null,null,null,null,null,{"$f":"D133","v":0}]
[null,"Our Name",null,null,"Address",null,null,null,null,null,"Phone"]
[]
["In case of emergency, you will contact the following person:"]
[]
[]
["Name",null,null,null,"Address",null,null,null,null,null,"Phone"]
[]
["We will maintain the apartment and all equipment provided with it, as well as "]
["common areas, facilities and equipment provided for your use and benefit, in "]
["compliance with Housing Quality Standards on the basis of which this Lease was "]
["approved by the DMHAS, and respond in a reasonable time to your calls for "]
["services consistent with said obligation.  Where applicable (as in case of multi-"]
["unit buildings), such maintenance with respect to common areas, facilities and "]
["equipment shall include cleaning, maintenance of lighting and equipment, "]
["maintenance of grounds, lawns and shrubs; and removal of snow and ice.  Where "]
["security equipment and services are to be provided by us, they are as follows:"]
[]
[]
["(Specify, or state “No schedule”)."]
[]
["Extermination services will be provided by us as conditions may require.  If such services "]
["are to be provided on a scheduled basis, the schedule is as follows:"]
[]
[]
["(Specify, or state “No schedule”)."]
[]
["Repairs:","We agree to complete the repairs listed below by the following dates:"]
["#1.",null,null,null,null,null,null,null,null,"#1."]
["#2.",null,null,null,null,null,null,null,null,"#2."]
["#3.",null,null,null,null,null,null,null,null,"#3."]
["#4.",null,null,null,null,null,null,null,null,"#4."]
["#5.",null,null,null,null,null,null,null,null,"#5."]
[null,"Repair",null,null,null,null,null,null,null,null,"Date"]
[]
["We hereby notify you that an operative fire sprinkler system (does/does not) "]
[]
[]
["If an operative fire sprinkler system exists at the apartment in accordance "]
["with the foregoing paragraph, its last day of maintenance and inspection was "]
[]
["Enter Date or enter N/A"]
[]
[]
[]
["Occupancy Continuation Form 1"]
[]
["Telephone Nos.  Home",null,null,{"$f":"C14","v":0},null,null,"Work",{"$f":"C15","v":0},null,null,"Date"]
[]
["Family","Name of Persons to Live in unit",null,null,null,"Relation to Family Head","Sex","Date of Birth","Student Yes/No",null,"Social Security #"]
["Member"]
["No."]
[]
["Head",{"$f":"B8","v":0},null,null,null,"Self",null,{"$f":"IF(C16<>\"\", C16, \"\")","v":""},null,null,{"$f":"D17","v":0}]
[2]
[3]
[4]
[5]
[6]
[7]
[]
["List any changes expected in household:"]
["List School(s) attended by Students:"]
[]
[]
[]
["GROSS INCOME AND EMPLOYMENT: List everyone who is receiving income and/or working."]
["You must include all income from employment, tips, TANF, pension, social security, unemployment "]
["compensation, alimony, child support, educational stipends, veterans’ benefits, SNAP, Medicare/Medicaid "]
["and/or any other public assistance.  "]
[]
["Family ",null,"Source of Income for"]
["Member No.",null,"All Family Members",null,null,"Amount",null,null,"Per"]
["Head"]
[]
[]
[]
[]
[]
[]
[]
["EMERGENCY CONTACT INFORMATION:  List person (family member, friend, sponsor, etc.) who you "]
["would like CoC Rental Assistance Program to contact in case of any emergencies."]
["Emergency Contact:",null,null,null,null,null,null,null,null,"Telephone #",null,null,null,null,null,"-"]
[]
["Address:   "]
[]
["Occupancy Continuation Form 2"]
["Assets"]
[]
["List all checking and savings accounts (including IRAs, Keogh accounts, and Certificate of Deposit). List the "]
["value of all stocks, bonds, trusts, pensions, or other assets owned by any household member."]
[]
["Family",null,"Bank Name",null,null,"Type of "]
["Member",null,null,null,null,"Account",null,"Balance"]
["Head"]
[2]
[3]
["Yes",null,"Do you have expenses for child care of a child aged 12 or younger?"]
["No",null,"If yes, provide the name, address and telephone number of the care provider:"]
[]
[]
[]
[]
[null,null,"What is the weekly cost to you of the child care? "]
[]
[null,null,"Do you pay a care attendant or for any equipment for any handicapped or "]
[null,null,"disabled family member(s) necessary to permit that person or someone \telse in "]
[null,null,"the household to work? If so, what is the cost to you for the care attendant and/or "]
[null,null,"the equipment?  "]
[]
["Yes",null,"Do you have outstanding medical bills which you are paying? If yes list "]
["No",null,"them below."]
[]
[]
[]
[null,null,"What medical expenses do you expect to incur in the next twelve months?"]
[]
[]
[]
["Yes",null,"Do you have a conservator (of person or finances)?  If so please provide the "]
["No",null,"name, address and type of conservator:"]
[]
[]
[]
[]
["Tenant Signature"]
[]
["Date:"]
[]
[]
[]
["Payment Notification Approval"]
[]
[]
["Date"]
[]
[{"$f":"Administration!C123","v":0}]
[{"$f":"C124&\" \"&Sheet2!J2&\" \"&Administration!C125","v":"0  0"}]
[{"$f":"Administration!E125&\" \"&Administration!G125&\" \"&Administration!I125","v":"0 0 0"}]
[]
["Head of household name:",null,null,{"$f":"C123&\",\"","v":"0,"}]
[]
["The Monthly Contract Rent for the unit rented from ",null,null,null,null,{"$f":"C129","v":0}]
[]
[]
["Term beginning",null,{"$f":"IF(F152<>\"\", F152, \"\")","v":""},null,"and ending",{"$f":"IF(H152<>\"\", H152, \"\")","v":""}]
[]
["Contract Rent is",null,{"$f":"D148","v":0},"tenant portion is",null,{"$f":"D146","v":0}]
[]
["Name and title of housing staff filling out this form:"]
["Name of housing office"]
["Phone number of the staff filling out this form:"]
[]
["PC:"]
[]
[]
[]
[]
["Rent Reasonableness Checklist and Certification"]
["Name:",{"$f":"B8","v":0},null,"Proposed Unit",null,"Unit #1",null,"Unit #2",null,"Unit #3"]
["Address",null,null,{"$f":"C9&\" \"&Sheet2!J2&\" \"&B10&\" \"&B11&\" \"&B12&\" \"&B13","v":"     "}]
[]
[]
[]
["Number of bedrooms"]
["Square Feet"]
["Type of Unit/Construction"]
[]
["Housing Condition"]
["Location/Accessibility"]
[]
[]
[]
[]
[]
["Amenities"]
[]
["Unit:"]
[]
["Site:"]
[]
["Neighborhood"]
[]
["Age in years"]
["Utilities (type)"]
[]
[]
[]
[]
[]
["Unit Rent",null,null,{"$f":"C108","v":0}]
["Utility Allowance",null,null,{"$f":"'Calculation Worksheet Page 2'!H39","v":0}]
["Gross Rent",null,null,{"$f":"SUM(D423:E424)","v":0},null,{"$f":"SUM(F423:G424)","v":0},null,{"$f":"SUM(H423:I424)","v":0},null,{"$f":"SUM(J423:K424)","v":0},null,{"$f":"IF(AND(F425<D425,H425<D425,J425<D425),\"flag\",\"\")","v":""}]
["Handicap Accessible?"]
[]
[null,"CERTIFICATION:"]
[]
[null,"A.","Compliance with Payment Standard"]
[]
[null,{"$f":"D148","v":0},null,null,{"$f":"'Calculation Worksheet Page 2'!H39","v":0},null,{"$f":"B432+E432","v":0}]
[null,"Proposed Contract rent      +",null,null,"Utility Allowance      =",null,"Proposed Gross Rent"]
[]
[null,"Approved rent does exceed Fair Market Rent (FMR) of",null,null,null,{"$f":"C107","v":0}]
[]
[]
[]
[null,"If the proposed gross rent exceeds the FMR is it less than or equal to the gross rent of "]
[null,"each comparable unit shown above?",null,null,"Indicate YES or NO"]
[]
[]
[null,"B. Rent Reasonableness"]
[null,"Based upon a comparison with rents for comparable units, I have determined that the "]
[null,"proposed rent for the unit ",null,"    is","         is not reasonable"]
[]
[]
[null,"Name:",null,null,null,null,null,"Date:"]
[]
[]
[]
["Notification of Annual Review"]
[]
["Date"]
[]
["Indicate date that the lease expires:"]
[]
["Tenant Name:",null,{"$f":"B8&\",\"","v":","}]
[]
["Name of housing staff:"]
["Title of housing staff:"]
["Phone number of staff of staff filling out the form:"]
[]
[]
["Date of annual inspection:"]
["Time of annual inspection appointment:"]
["Day of the week of annual inspection:"]
[]
[]
[]
["DMHAS CoC RENTAL ASSISTANCE PROGRAM CONTRACT AMENDMENT"]
[]
["Contract Number:",null,{"$f":"C5","v":0}]
[]
["Effective Date:",null,{"$f":"IF(F152<>\"\", F152, \"\")","v":""}]
[]
["Terminating on:",null,{"$f":"IF(H152<>\"\", H152, \"\")","v":""}]
[]
["Owner name:",null,{"$f":"B21","v":0}]
[]
["Tenant Name: ",null,{"$f":"B8","v":0}]
[]
["Tenant address ",null,{"$f":"C9&\" \"&Sheet2!J2&\" \"&B10&\" \"&B11&\" \"&B12&\" \"&B13","v":"     "}]
[]
["Security Deposit Amount:",null,null,{"$f":"D149","v":0}]
[]
["Security deposit funds from: ",null,null,{"$f":"D190","v":0}]
[]
["New Owner Name:"]
["New Owner Supplier ID:"]
[]
["Effective Date of new owner:"]
[]
["Enter amount of housing assistance payment:"]
[]
[]
[]
[]
["VAWA Lease Addendum"]
[]
["Unit No. & Address",null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10&\" \"&Administration!B11&\" \"&Administration!B12&\" \"&Administration!B13","v":"     "}]
[]
["Effective date of this Lease addendum is ",null,null,null,{"$f":"IF(Administration!F152<>\"\", Administration!F152, \"\")","v":""}]

{"sheet":"Calculator","index":1,"n_rows":71,"n_cols":30,"rows_kept":71,"cut":false,"hidden":false,"merged":[[49,17,49,23],[47,24,48,28],[49,24,49,28],[49,0,49,3],[47,4,48,11],[47,0,48,3],[49,4,49,11],[47,12,48,16],[47,17,48,23],[51,0,52,3],[49,12,49,16],[53,0,53,3],[53,4,53,11],[53,12,53,16],[53,17,53,23],[53,24,53,28],[53,29,53,34],[51,4,52,11],[51,12,52,16],[51,17,52,23],[55,24,56,28],[55,29,56,34],[57,29,57,34],[47,29,48,34],[51,24,52,28],[51,29,52,34],[49,29,49,34],[68,12,69,18],[68,19,69,23],[68,24,69,29],[68,0,69,3],[68,4,69,11],[70,0,70,3],[70,4,70,11],[70,12,70,18],[70,19,70,23],[70,24,70,29],[66,0,66,3],[66,4,66,11],[66,24,66,29],[66,12,66,18],[66,19,66,23],[64,0,65,3],[64,4,65,11],[64,12,65,18],[64,19,65,23],[64,24,65,29],[60,24,61,29],[60,12,61,18],[60,19,61,23],[62,0,62,3],[62,4,62,11],[62,12,62,18],[62,19,62,23],[62,24,62,29],[55,4,56,11],[55,12,56,16],[55,17,56,23],[60,0,61,3],[60,4,61,11],[28,7,28,10],[28,20,28,22],[28,23,28,25],[42,36,42,38],[57,0,57,3],[57,4,57,11],[57,12,57,16],[30,14,30,17],[30,20,30,22],[30,23,30,25],[32,10,32,12],[32,19,32,22],[32,23,32,25],[57,17,57,23],[57,24,57,28],[55,0,56,3],[22,19,22,20],[23,0,24,27],[26,7,26,10],[26,20,26,22],[26,23,26,25],[32,13,32,18],[0,19,0,20],[0,22,0,30],[1,0,2,27],[4,0,4,6],[4,7,4,10],[22,22,22,30],[5,0,5,6],[5,7,5,10],[7,11,7,16],[9,13,9,18],[9,19,9,25],[12,8,12,10],[14,8,14,10],[16,0,16,6],[16,8,16,10]]}
["Pro-rate calculator:  move-in mid-month",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Todays Date:",{"$f":"TODAY()","v":"2024-04-01"}]
["Please Note: The #VALUE! error will be displayed in certain cells when the sections highlighted in yellow are left empty. This error will disappear, and the cells will show the appropriate values as soon as all necessary inputs are provided and calculations are completed."]
[]
[]
["Enter full contract rent:"]
["Enter full HAP amount:"]
[]
["The month and year the contract started is:",null,null,null,null,null,null,null,null,null,null,{"$f":"IF(ISBLANK(N10),\"\",DATE(YEAR(N10),MONTH(N10),1))","v":""}]
[]
["Enter full numerical date that the contract started:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(N10=\"\", \"\", IF(ISNUMBER(N10), IF(OR(DAY(N10)>31, MONTH(N10)>12, YEAR(N10)<1900, YEAR(N10)>9999), \"Invalid Date\", \"\"), \"Invalid Date or Format\"))","v":""}]
["Example:  2/20/2024"]
[]
["Pro-Rated Contract Rent:",null,null,null,null,null,null,null,{"$f":"CEILING(Calculator!AD58,1)","v":{"$error":"#VALUE!"}}]
[]
["Pro-Rated Tenant Portion is: ",null,null,null,null,null,null,null,{"$f":"FLOOR(Calculator!AD54,1)","v":{"$error":"#VALUE!"}}]
[]
["Pro-Rated HAP amount is:",null,null,null,null,null,null,null,{"$f":"I13-I15","v":{"$error":"#VALUE!"}}]
[]
["Number of days the unit is occupied",null,null,null,null,null,null,null,null,null,{"$f":"Calculator!Y50","v":""}]
[]
[]
[]
["Pro-rate calculator:  move-out mid-month",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Todays Date:",{"$f":"TODAY()","v":"2024-04-01"}]
["Please Note: The #VALUE! error will be displayed in certain cells when the sections highlighted in yellow are left empty. This error will disappear, and the cells will show the appropriate values as soon as all necessary inputs are provided and calculations are completed."]
[]
[]
["Enter full contract rent:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pro-Rated Contract Rent is:",null,null,{"$f":"CEILING(Calculator!Y71,1)","v":{"$error":"#VALUE!"}}]
[]
["Enter full HAP amount:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pro-Rated Tenant Portion is:",null,null,{"$f":"FLOOR(Calculator!Y67,1)","v":{"$error":"#VALUE!"}}]
[]
["The move out date's corresponding month's first day is:",null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(ISBLANK(K33),\"\",DATE(YEAR(K33),MONTH(K33),1))","v":""},null,null,null,null,null,"Pro-Rated HAP amount is:",null,null,{"$f":"X27-X29","v":{"$error":"#VALUE!"}}]
[]
["Enter full numerical move out date:",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(K33=\"\", \"\", IF(ISNUMBER(K33), IF(OR(DAY(K33)>31, MONTH(K33)>12, YEAR(K33)<1900, YEAR(K33)>9999), \"Invalid Date\", \"\"), \"Invalid Date or Format\"))","v":""},null,null,null,null,null,"Number of days the unit is occupied",null,null,null,{"$f":"Calculator!T63","v":{"$error":"#VALUE!"}}]
["Example: 2/15/2024",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(AND(ISNUMBER(O31),ISNUMBER(K33)),IF(OR(MONTH(O31)<>MONTH(K33),YEAR(O31)<>YEAR(K33)),\"Date Error\",\"\"),\"\")","v":""}]
[]
[]
[]
[{"$f":"Administration!A2","v":"Version 2.1"}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["HAP amount",null,null,null,"Month and year the contract started",null,null,null,null,null,null,null,"Days in month",null,null,null,null,"Date the lease and contract started ",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated HAP amount"]
[]
[{"$f":"Calculator!H6","v":0},null,null,null,{"$f":"IF(Calculator!L8<>\"\",Calculator!L8,\"\")","v":""},null,null,null,null,null,null,null,{"$f":"DAY(EOMONTH(E50,0))","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"IF(Calculator!N10<>\"\",Calculator!N10,\"\")","v":""},null,null,null,null,null,null,{"$f":"IF(ISNUMBER(R50), EOMONTH(R50,0)-R50+1, \"\")","v":""},null,null,null,null,{"$f":"IF(OR(ISBLANK(A50), ISBLANK(M50), ISBLANK(Y50), NOT(ISNUMBER(A50)), NOT(ISNUMBER(M50)), NOT(ISNUMBER(Y50)), M50=0), \"\", IFERROR(A50/M50*Y50, \"\"))","v":{"$error":"#VALUE!"}}]
[]
["Tenant Portion ",null,null,null,"Month and year the contract started",null,null,null,null,null,null,null,"Days in month",null,null,null,null,"Date the lease and contract started ",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated Tenant Portion"]
[]
[{"$f":"Calculator!H5-Calculator!H6","v":0},null,null,null,{"$f":"IF(Calculator!L8<>\"\",Calculator!L8,\"\")","v":""},null,null,null,null,null,null,null,{"$f":"DAY(EOMONTH(E54,0))","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"IF(Calculator!N10<>\"\",Calculator!N10,\"\")","v":""},null,null,null,null,null,null,{"$f":"IF(ISNUMBER(R54), EOMONTH(R54,0)-R54+1, \"\")","v":""},null,null,null,null,{"$f":"IF(OR(ISBLANK(A54), ISBLANK(M54), ISBLANK(Y54), NOT(ISNUMBER(A54)), NOT(ISNUMBER(M54)), NOT(ISNUMBER(Y54)), M54=0), \"\", IFERROR(A54/M54*Y54, \"\"))","v":{"$error":"#VALUE!"}}]
[]
["Contract Rent",null,null,null,"Month and year the contract started",null,null,null,null,null,null,null,"Days in month",null,null,null,null,"Date the lease and contract started ",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated Contract Rent"]
[]
[{"$f":"Calculator!H5","v":0},null,null,null,{"$f":"Calculator!L8","v":""},null,null,null,null,null,null,null,{"$f":"DAY(EOMONTH(E58,0))","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"Calculator!N10","v":"00:00:00"},null,null,null,null,null,null,{"$f":"IF(ISNUMBER(R58), EOMONTH(R58,0)-R58+1, \"\")","v":32},null,null,null,null,{"$f":"IF(OR(ISBLANK(A58), ISBLANK(M58), ISBLANK(Y58), NOT(ISNUMBER(A58)), NOT(ISNUMBER(M58)), NOT(ISNUMBER(Y58)), M58=0), \"\", IFERROR(A58/M58*Y58, \"\"))","v":{"$error":"#VALUE!"}}]
[]
[]
["HAP amount",null,null,null,"Move in date",null,null,null,null,null,null,null,"Move out date",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated Contract Rent"]
[]
[{"$f":"Calculator!H29","v":0},null,null,null,{"$f":"IF(Calculator!O31<>\"\",Calculator!O31,\"\")","v":""},null,null,null,null,null,null,null,{"$f":"IF(Calculator!K33<>\"\",Calculator!K33,\"\")","v":""},null,null,null,null,null,null,{"$f":"(M63-E63)+1","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"(A63/DAY(EOMONTH(E63,0)))*T63","v":{"$error":"#VALUE!"}}]
[]
["Tenant portion",null,null,null,"Move in date",null,null,null,null,null,null,null,"Move out date",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated Tenant Portion"]
[]
[{"$f":"Calculator!H27-Calculator!H29","v":0},null,null,null,{"$f":"IF(Calculator!O31<>\"\",Calculator!O31,\"\")","v":""},null,null,null,null,null,null,null,{"$f":"IF(Calculator!K33<>\"\",Calculator!K33,\"\")","v":""},null,null,null,null,null,null,{"$f":"(M67-E67)+1","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"(A67/DAY(EOMONTH(E67,0)))*T67","v":{"$error":"#VALUE!"}}]
[]
["Contract Rent",null,null,null,"Move in date",null,null,null,null,null,null,null,"Move out date",null,null,null,null,null,null,"Number of days the unit is occupied",null,null,null,null,"Pro-Rated Contract Rent"]
[]
[{"$f":"Calculator!H27","v":0},null,null,null,{"$f":"IF(Calculator!O31<>\"\",Calculator!O31,\"\")","v":""},null,null,null,null,null,null,null,{"$f":"IF(Calculator!K33<>\"\",Calculator!K33,\"\")","v":""},null,null,null,null,null,null,{"$f":"(M71-E71)+1","v":{"$error":"#VALUE!"}},null,null,null,null,{"$f":"(A71/DAY(EOMONTH(E71,0)))*T71","v":{"$error":"#VALUE!"}}]

{"sheet":"Sheet2","index":2,"n_rows":504,"n_cols":16384,"rows_kept":504,"cut":false,"hidden":true,"merged":[]}
[]
["2024-03-06T08:35:01",null,null,null,null,null,null,null,null,{"$f":"IF(Administration!B10<>\"\",\"Apt #\",\"\")","v":""}]
["Grant information"]
[null,null,null,"2024-04-01T12:48:16","2024-04-01T12:48:16"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[]
[]
["Tenant Information","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[]
[]
["Landlord Information","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11","2024-04-01T12:48:11","2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:11"]
[null,"2024-04-01T12:48:12"]
[]
[null,null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,"Cal page 1","2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12",null,null,null,null,"2024-04-01T12:48:12"]
[null,null,null,null,null,null,"2024-04-01T12:48:12"]
[]
[]
[]
[]
[]
[]
[null,"Calculation worksheet page 2","2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,null,null,{"$f":"C9","v":"2024-04-01T12:48:11"}]
[null,null,"2024-04-01T12:48:12",null,null,null,{"$f":"B10","v":"2024-04-01T12:48:11"}]
[null,null,"2024-04-01T12:48:12",null,null,null,{"$f":"B11","v":"2024-04-01T12:48:11"}]
[null,null,"2024-04-01T12:48:12",null,null,null,"2024-04-01T12:48:11"]
[null,null,null,null,null,null,"2024-04-01T12:48:11"]
[]
[null,null,null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[]
[]
[]
[]
[null,null,null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[]
[]
[]
[]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
[]
[]
[null,null,"2024-04-01T12:48:12"]
[null,null,"2024-04-01T12:48:12"]
[]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["2024-03-13T14:10:45",null,null,null,"2024-03-13T14:10:44",null,null,"2024-03-13T14:10:44"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,"2024-03-13T14:10:43"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,"NAF"]
[null,null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12",null,null,null,null,null,null,{"$f":"D4","v":"2024-04-01T12:48:16"},{"$f":"C14","v":"2024-04-01T12:48:11"}]
["2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26","2024-03-04T13:00:26",null,{"$f":"D27","v":"2024-04-01T12:48:12"}]
[null,null,null,null,null,"2024-03-04T10:02:25",null,"2024-03-04T10:02:25",null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12",{"$f":"C16","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,"2024-04-01T12:48:12",null,"2024-04-01T12:48:12",null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12"]
["2024-03-06T10:35:02","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-06T10:34:41","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:29","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:30","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:31","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:32","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:33","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:34","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:35","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:36","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:37","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:38","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:39","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:40","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:41","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:42","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:43","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:44","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:45","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:46","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:47","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:48","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:49","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:50","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:51","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:52","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:53","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:54","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:55","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:56","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:57","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:58","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:49:59","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:00","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:01","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:02","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:03","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:04","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:05","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:06","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:07","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:08","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:09","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:10","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:11","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:12","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:13","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:14","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:15","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:16","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:17","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:18","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:19","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:20","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21","2024-03-04T12:50:21"]
["2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:34:41","2024-03-06T10:34:41"]
["2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:34:41","2024-03-06T10:34:41"]
["2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:24","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25"]
["2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25"]
["2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25",{"$f":"B23","v":"2024-04-01T12:48:11"}]
["2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25","2024-03-06T10:35:25",{"$f":"B24","v":"2024-04-01T12:48:11"}]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12",null,"2024-04-01T12:48:12"]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12",null,{"$f":"C22","v":"2024-04-01T12:48:11"}]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12",null,{"$f":"C22","v":"2024-04-01T12:48:11"},{"$f":"C28","v":"2024-04-01T12:48:12"}]
[null,null,"2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:12","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,null,{"$f":"C29","v":"2024-04-01T12:48:12"}]
[null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,"HAP Contract"]
[]
[null,null,null,"2024-03-04T10:02:25",null,{"$f":"C9","v":"2024-04-01T12:48:11"},{"$f":"F151","v":"2024-03-04T10:02:25"}]
[null,null,null,null,null,{"$f":"B10","v":"2024-04-01T12:48:11"},{"$f":"H151","v":"2024-03-04T10:02:25"}]
[null,null,null,"2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25"]
[null,null,null,"2024-03-06T08:43:51",null,{"$f":"B12","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,"2024-04-01T12:48:11"]
[null,null,null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
[]
[]
[null,null,null,"2024-04-01T12:48:13"]
[]
[null,null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[]
[]
[]
["Lease"]
[null,null,null,"2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25"]
[null,null,null,null,null,{"$f":"B10","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,{"$f":"B11","v":"2024-04-01T12:48:11"}]
[null,null,null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,null,null,null,null,"2024-04-01T12:48:11"]
[]
[]
[]
[]
[null,null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-03-04T10:02:25"]
[null,null,null,"2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:25"]
[]
[null,null,null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,null,null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
[]
[]
[null,null,"2024-03-04T10:02:25"]
[null,null,"2024-03-04T10:02:25","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,null,"2024-03-04T10:02:25","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-03-06T08:43:51"]
[null,null,"2024-04-01T12:48:13"]
[null,null,"2024-04-01T12:48:13"]
[null,null,"2024-04-01T12:48:13"]
[null,null,"2024-04-01T12:48:13"]
[null,null,"2024-04-01T12:48:13"]
[null,null,"2024-04-01T12:48:13"]
["2024-03-04T10:02:25","2024-03-04T10:02:25","2024-04-01T12:48:13",null,"2024-03-04T10:02:25","2024-03-04T10:02:25","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26",null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[]
[]
["2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
[]
[]
[]
[]
["2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[]
[]
["2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
[]
[]
["2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
[]
["2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
[]
[]
["2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26",null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26",null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26",null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
["2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51",null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
["2024-03-04T10:02:26","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13",null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
["2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,null,null,null,null,"2024-04-01T12:48:13","2024-04-01T12:48:13"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[]
["2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,null,null,null,null,null,null,null,null,null,null,"2024-03-06T08:43:51","2024-03-06T08:43:51"]
[]
["Occupancy continuation form 1"]
[null,null,null,null,null,null,"2024-03-04T10:02:26",null,"2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
[null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-06T08:43:51","2024-03-04T10:02:26","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-04T10:02:26","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
[null,"2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-04-01T12:48:13","2024-03-06T08:43:51","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-03-06T08:43:51","2024-03-06T08:43:51","2024-03-06T08:43:51"]
["2024-03-04T10:02:26","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
["2024-03-06T08:43:52","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13"]
[null,"2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:13","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
["2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
["2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-04T10:02:26"]
["2024-03-04T10:02:26","2024-03-04T10:02:26","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-03-06T08:43:52","2024-03-06T08:43:52","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14",null,"2024-03-04T10:02:27","2024-03-04T10:02:27"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14",null,"2024-03-06T08:43:52","2024-03-06T08:43:52"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[]
[]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14",null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
["Occupancy Continuation forms 2",null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[null,null,null,null,"2024-03-04T10:02:27"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,"2024-03-06T08:43:52"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,null,null,"2024-04-01T12:48:14"]
[]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[null,null,"2024-03-04T10:02:27"]
[null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[]
[null,"2024-03-04T10:02:27","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[]
[null,null,"2024-04-01T12:48:14"]
[null,"2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[]
[]
[]
[]
["Payment notification approval","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,null,null,{"$f":"C9","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,null,{"$f":"B10","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,null,{"$f":"B11","v":"2024-04-01T12:48:11"}]
[null,null,null,null,null,null,"2024-04-01T12:48:11"]
[null,null,null,null,null,null,"2024-04-01T12:48:11"]
[null,null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,null,null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[]
[null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,"2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14"]
[null,null,null,null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,null,null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-04T10:02:27"]
[null,"2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-04-01T12:48:14","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52","2024-03-06T08:43:52"]
[null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-06T08:43:52","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,"2024-03-04T10:02:27","2024-03-04T10:02:27","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["Rent R",null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"D392","v":"2024-03-06T08:43:53"},null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"D393","v":"2024-03-06T08:43:53"},null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"F392","v":"2024-03-06T08:43:53"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"F393","v":"2024-04-01T12:48:15"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"H384","v":"2024-03-04T10:02:27"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"H388","v":"2024-03-06T08:43:53"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-04-01T12:48:15",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"J384","v":"2024-03-04T10:02:27"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[{"$f":"J388","v":"2024-03-06T08:43:53"},null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-03-06T08:43:53",null,{"$f":"C439","v":"2024-03-04T10:02:28"},"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
["2024-04-01T12:48:15",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[]
[null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[]
[]
[]
[]
[null,null,null,null,null,null,null,"2024-03-04T10:02:28"]
[]
[]
[null,null,null,null,null,null,null,"2024-03-06T08:43:53"]
[]
[]
[]
[]
[null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28",null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28"]
[null,null,null,null,"2024-03-07T09:44:57","2024-04-01T12:48:15",null,"2024-03-07T10:13:52"]
[]
[null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53",null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,"2024-03-07T09:45:20","2024-03-07T09:45:17"]
[]
[null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-07T09:46:04","2024-03-07T09:46:55","2024-03-07T09:46:40","2024-03-07T09:46:40","2024-03-07T09:46:40"]
[]
[null,null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28"]
[null,"2024-03-06T08:43:53","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15",null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[]
[null,null,null,"2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28"]
[null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28"]
[null,null,null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28","2024-03-04T10:02:28"]
["Annual notification review","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[{"$f":"B445","v":"2024-03-04T10:02:28"},{"$f":"D447","v":"2024-03-04T10:02:28"},"2024-03-06T08:43:53","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[{"$f":"E453","v":"2024-03-04T10:02:28"},null,{"$f":"C452","v":"2024-03-04T10:02:28"},"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-03-06T08:43:53","2024-03-06T08:43:53"]
[null,null,null,null,"2024-03-04T10:02:28"]
[{"$f":"C9","v":"2024-04-01T12:48:11"},null,null,null,"2024-03-04T10:02:28"]
[null,null,null,null,"2024-03-06T08:43:53"]
[null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[null,null,null,null,"2024-04-01T12:48:15","2024-04-01T12:48:15","2024-04-01T12:48:15"]
[]
[]
[null,null,null,null,"2024-04-01T12:48:15"]
[null,null,null,null,"2024-04-01T12:48:15"]
[null,null,null,null,"2024-04-01T12:48:16"]
[]
[]
[]
[]
[]
["Conract A"]
[{"$f":"C5","v":"2024-04-01T12:48:11"}]
[{"$f":"F151","v":"2024-03-04T10:02:25"},{"$f":"H151","v":"2024-03-04T10:02:25"}]
[]
[{"$f":"C22","v":"2024-04-01T12:48:11"}]
[]
[{"$f":"C9","v":"2024-04-01T12:48:11"}]
[null,null,"2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29"]
[null,null,"2024-03-04T10:02:28","2024-03-04T10:02:28"]
[{"$f":"B10","v":"2024-04-01T12:48:11"}]
[{"$f":"B11","v":"2024-04-01T12:48:11"},null,"2024-03-06T08:43:53","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54"]
["2024-04-01T12:48:11",null,"2024-03-06T08:43:54","2024-03-06T08:43:54"]
["2024-04-01T12:48:11",null,null,null,"2024-03-04T10:02:29"]
[null,null,null,"2024-03-06T08:43:54","2024-03-06T08:43:54"]
[null,null,"2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29","2024-03-04T10:02:29"]
[{"$f":"D149","v":"2024-04-01T12:48:12"},null,null,null,"2024-03-06T08:43:54"]
[null,null,"2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16","2024-04-01T12:48:16"]
[{"$f":"D181","v":"2024-03-04T10:02:25"},null,"2024-04-01T12:48:16","2024-04-01T12:48:16","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54","2024-03-06T08:43:54"]
[]
[null,null,null,"2024-04-01T12:48:16","2024-04-01T12:48:16"]
[]
["Vawa",{"$f":"Sheet2!B10","v":"2024-04-01T12:48:11"},{"$f":"C22","v":"2024-04-01T12:48:11"},null,"2024-04-01T12:48:16"]
[null,{"$f":"Sheet2!B11","v":"2024-04-01T12:48:11"},null,null,"2024-03-04T10:02:29"]
["2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11","2024-03-13T15:18:11"]
[null,{"$f":"Sheet2!B13","v":"2024-04-01T12:48:11"}]
["2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42","2024-03-13T15:18:42"]
["2024-04-01T12:47:41"]
[]
[]
[]
[]
[null,null,null,null,"2024-03-06T10:44:31"]

{"sheet":"Calculation Worksheet Page 1","index":3,"n_rows":43,"n_cols":4,"rows_kept":43,"cut":false,"hidden":false,"merged":[[2,2,2,3],[11,2,11,3],[22,2,22,3],[31,2,31,3],[30,2,30,3]]}
[]
["Household Member #1",null,"Household Member #1"]
[null,"Monthly","Weekly Pay"]
["SSDI",{"$f":"Administration!G38","v":0},"Week 1 Pay",{"$f":"Administration!L39","v":0}]
["SSI",{"$f":"Administration!G39","v":0},"Week 2 Pay",{"$f":"Administration!L40","v":0}]
["TANF",{"$f":"Administration!G40","v":0},"Week 3 Pay",{"$f":"Administration!L41","v":0}]
["Earned Income",{"$f":"Administration!G41","v":0},"Week 4 Pay",{"$f":"Administration!L42","v":0}]
["SAGA",{"$f":"Administration!G42","v":0},"Total",{"$f":"SUM(D4:D7)","v":0}]
["Unemployment",{"$f":"Administration!G43","v":0},"Monthly Average",{"$f":"FLOOR(D8/4*52/12,1)","v":0}]
["Child Support",{"$f":"Administration!G44","v":0}]
["Alimony",{"$f":"Administration!G45","v":0},"Household Member #1"]
["VA Service- Connected Disability Compensation Income",{"$f":"Administration!G46","v":0},"Bi-Weekly Pay"]
["VA Non-Service Connected Disability Pension",{"$f":"Administration!G47","v":0},"Bi-Weekly 1st",{"$f":"Administration!L50","v":0}]
["Private Disability Insurance Income",{"$f":"Administration!G48","v":0},"Bi-Weekly 2nd",{"$f":"Administration!L51","v":0}]
["Retirement Income from Social Security Income",{"$f":"Administration!G49","v":0},"Total",{"$f":"SUM(D13,D14)","v":0}]
["Pension/ Retirement Income from a former job",{"$f":"Administration!G50","v":0},"Monthly Average",{"$f":"FLOOR(D15/2*26/12,1)","v":0}]
["Worker's Compensation",{"$f":"Administration!G51","v":0}]
["Other sources of Income",{"$f":"Administration!G52","v":0}]
[null,{"$f":"SUM(B4:B18)","v":0}]
[]
[]
["Household Member #2",null,"Household Member #2"]
[null,"Monthly","Weekly Pay"]
["SSDI",{"$f":"Administration!G59","v":0},"Week 1 Pay",{"$f":"Administration!L60","v":0}]
["SSI",{"$f":"Administration!G60","v":0},"Week 2 Pay",{"$f":"Administration!L61","v":0}]
["TANF",{"$f":"Administration!G61","v":0},"Week 3 Pay",{"$f":"Administration!L62","v":0}]
["Earned Income",{"$f":"Administration!G62","v":0},"Week 4 Pay",{"$f":"Administration!L63","v":0}]
["SAGA",{"$f":"Administration!G63","v":0},"Total",{"$f":"SUM(D24:D27)","v":0}]
["Unemployment",{"$f":"Administration!G64","v":0},"Monthly Average",{"$f":"D28/4*52/12","v":0}]
["Child Support",{"$f":"Administration!G65","v":0}]
["Alimony",{"$f":"Administration!G66","v":0},"Household Member #2"]
["VA Service- Connected Disability Compensation Income",{"$f":"Administration!G67","v":0},"Bi-Weekly Pay"]
["VA Non-Service Connected Disability Pension",{"$f":"Administration!G68","v":0},"Bi-Weekly 1st",{"$f":"Administration!L71","v":0}]
["Private Disability Insurance Income",{"$f":"Administration!G69","v":0},"Bi-Weekly 2nd",{"$f":"Administration!L72","v":0}]
["Retirement Income from Social Security Income",{"$f":"Administration!G70","v":0},"Total",{"$f":"SUM(D33,D34)","v":0}]
["Pension/ Retirement Income from a former job",{"$f":"Administration!G71","v":0},"Monthly Average",{"$f":"FLOOR(D35/2*26/12,1)","v":0}]
["Worker's Compensation",{"$f":"Administration!G72","v":0}]
["Other sources of Income",{"$f":"Administration!G73","v":0}]
[null,{"$f":"SUM(B24:B38)","v":0}]
[]
["Last Edited"]
[{"$f":"LARGE(Sheet2!G38:L75,1)","v":"2024-04-01T12:48:12"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Calculation Worksheet Page 2","index":4,"n_rows":47,"n_cols":8,"rows_kept":47,"cut":false,"hidden":false,"merged":[[32,1,32,4],[45,0,45,1],[45,2,45,5],[34,1,34,4],[35,1,35,4],[33,1,33,4],[37,3,37,4],[36,3,36,4],[1,6,1,7],[0,6,0,7],[3,3,3,5],[10,0,10,1],[19,0,20,4],[4,3,4,5],[7,1,7,5],[6,1,6,5],[0,4,0,5],[1,4,1,5]]}
["Date:",{"$f":"Administration!C80","v":"00:00:00"},null,null,"Certificate Number:",null,{"$f":"Administration!C81","v":0}]
[null,null,null,null,"Contract Number:",null,{"$f":"IF(Administration!C5<>\"\", Administration!C5, \"\")","v":""}]
[]
[null,null,null,"Rental Assistance Payments"]
[null,null,null,"Calculation Worksheet"]
[]
["Name:  ",{"$f":"Administration!C123","v":0},null,null,null,null,"# of Bedrooms:",{"$f":"Administration!C82","v":0}]
["Address: ",{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10&\" \"&Administration!B11&\" \"&Administration!B12&\" \"&Administration!B13","v":"     "},null,null,null,null,"# of Dependents:",{"$f":"Administration!C83","v":0}]
[null,null,null,null,null,null,"# in Household:",{"$f":"Administration!C84","v":0}]
[]
["1. Gross Annual Income: ",null,null,null,null,null,null,{"$f":"+ROUNDDOWN(E12+E13,0)","v":0}]
["  Household Member #1:",null,{"$f":"'Calculation Worksheet Page 1'!B19","v":0},"Monthly",{"$f":"+C12*12","v":0},"Yearly"]
["  Household Member #2:",null,{"$f":"'Calculation Worksheet Page 1'!B39","v":0},"Monthly",{"$f":"+C13*12","v":0},"Yearly"]
[]
["    A. 10% of Gross Annual Income divided by 12 months",null,null,null,null,null,null,{"$f":"+ROUNDDOWN(H11*0.1/12,0)","v":0}]
["    B. Total Utility Allowance from #6",null,null,null,null,null,null,{"$f":"H39","v":0}]
["    C. 10 % of Gross Monthly Income (line 1A) minus Total utility allowance",null,null,null,null,null,null,{"$f":"+H15-H16","v":0}]
["2. Annual Allowances"]
["    A. Each Dependent ",null,480,null,null,null,null,{"$f":"IF(H8=0,0,H8*C19)","v":0}]
["    B. For Child Care: (Costs which enable one or both parents to be gainfully employed)",null,null,null,null,null,null,{"$f":"Administration!E87","v":0}]
[]
["    C. Non-reimbursed Medical Expenses in excess of 3% of Gross Income:"]
[null,"a. Non-reimbursed Medical Expenses",null,null,null,null,null,{"$f":"Administration!E92","v":0}]
[null,"b. Less 3% of Annual Income",null,null,null,null,null,{"$f":"IF(H23>0,+H11*0.03,0)","v":0}]
[null,"c. Deduction (greater than zero) a - b = #2c",null,null,null,null,null,{"$f":"IF(H23-H24>0,(H23-H24),0)","v":0}]
["    D. Allowances for Elderly and Disabled ",null,null,null,400,null,null,{"$f":"+E26","v":400}]
["    E. Total Allowances",null,null,null,null,null,null,{"$f":"ROUNDDOWN(H20+H19+H25+H26,0)","v":400}]
["3. Annual Income After Allowances",null,null,null,null,null,null,{"$f":"+ROUNDDOWN(H11-H27,0)","v":-400}]
["    A. Monthly income after allowances",null,null,null,null,null,null,{"$f":"+ROUNDDOWN(H28/12,0)","v":-33}]
["4. 30% of Monthly Income After Allowances",null,null,null,null,null,null,{"$f":"ROUNDDOWN(H29*0.3,0)","v":-9}]
["5. Contract Rent",null,null,null,null,null,null,{"$f":"Administration!C108","v":0}]
["6. Allowance for Utilities and Other Services"]
[null,"Heating:      Natural Gas/Bottle Gas/Oil/Electric",null,null,null,{"$f":"Administration!E97","v":0},null,{"$f":"Administration!G97","v":0}]
[null,"Water Heat: Natural Gas/Bottle Gas/Oil/Electric",null,null,null,{"$f":"Administration!E98","v":0},null,{"$f":"Administration!G98","v":0}]
[null,"Cooking:      Natural Gas/Bottle Gas/Oil/Electric",null,null,null,{"$f":"Administration!E99","v":0},null,{"$f":"Administration!G99","v":0}]
[null,"Other Electric: Lighting, refrigeration, etc.",null,null,null,{"$f":"Administration!E100","v":0},null,{"$f":"Administration!G100","v":0}]
["Appliances:     ","Range   ",{"$f":"Administration!E101","v":0},"    Refrigerator",null,{"$f":"Administration!E102","v":0},null,{"$f":"Administration!G101+Administration!G102","v":0}]
["Misc:  ","Water  ",{"$f":"Administration!E103","v":0},"    Trash Collection",null,{"$f":"Administration!E104","v":0},null,{"$f":"Administration!G103+Administration!G104","v":0}]
[null,"Total Utility Allowance",null,null,null,null,null,{"$f":"SUM(H33:H38)","v":0}]
["7. Gross Rent",null,null,null,null,null,null,{"$f":"H31+H39","v":0}]
["8. Fair Market Rent",null,null,null,null,null,null,{"$f":"Administration!C107","v":0}]
["9. Family Contribution",null,"The greater of either #1C",null,{"$f":"H17","v":0},"or #4-#6",{"$f":"H30-H39","v":-9},{"$f":"IF(G42 > H31, H31, MAX(E42, G42, 0))","v":0}]
["10. Subsidy Payment",null,null,null,null,null,null,{"$f":"IF(H42>0,H31-H42,H31)","v":0}]
[]
[]
["Preparer's typed name:",null,{"$f":"IF(Administration!C110<>\"\", Administration!C110, \"\")","v":""},null,null,null,"Last edited",{"$f":"LARGE(Sheet2!B81:G111,1)","v":"2024-04-01T12:48:12"}]
["rev.9/25/23",null,null,null,null,null,null,{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"NAF","index":5,"n_rows":49,"n_cols":16,"rows_kept":49,"cut":false,"hidden":false,"merged":[[47,0,47,1],[5,0,5,1],[5,2,5,6],[8,2,8,7],[8,9,8,11],[10,2,10,10],[45,10,45,11],[43,2,43,7],[45,2,45,7],[40,10,40,11],[42,10,42,11],[44,10,44,11],[43,10,43,11],[41,10,41,11],[44,0,44,1],[44,2,44,7],[25,0,25,1],[25,7,25,8],[26,4,26,5],[4,0,4,1],[4,10,4,11],[4,2,4,6],[6,1,6,2],[6,4,6,7],[23,2,23,3],[9,2,9,8],[13,2,13,12],[42,0,42,1],[40,0,40,1],[25,2,25,3],[12,2,12,12],[0,0,0,12],[1,0,1,12],[3,0,3,2],[3,3,3,7],[3,10,3,11],[3,8,3,9],[22,2,22,3],[19,2,19,3],[40,2,40,7],[42,2,42,7],[17,3,17,7],[24,2,24,3],[41,2,41,7],[14,3,14,7],[19,5,19,7],[20,7,20,10],[35,2,36,12],[25,11,26,12],[15,3,15,7],[16,2,16,7],[20,2,20,3]]}
["CoC RENTAL ASSISTANCE PROGRAM"]
["New Admission Form"]
["1. GRANT INFORMATION"]
["   Federal Grant I.D./HUD Award No.: ",null,null,{"$f":"Administration!E116","v":0},null,null,null,null,"SID NO. ",null,{"$f":"Administration!K116","v":22656}]
["   Contract No.:",null,{"$f":"Administration!C117","v":0},null,null,null,null,null,"Project No.     ",null,{"$f":"Administration!K117","v":{"$error":"#VALUE!"}}]
[]
[null,"       New Admission",null,null,"     Re-Certification",null,null,null,"             Current Participant New Address OR Unit"]
["2. TENANT INFORMATION",null,null,null,null,null,null,null,null,null,null,null,null,null,false,6]
["   Tenant's Account No.:",null,{"$f":"Administration!C122","v":0},null,null,null,null,null,null,"No of bedrooms:",null,null,{"$f":"Administration!I122","v":0},null,false,7]
["   Tenant's Name:",null,{"$f":"Administration!C123","v":0},null,null,null,null,null,null,null,null,null,null,null,false,8]
["   Address:",null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10&\" \"&Administration!B11&\" \"&Administration!B12&\" \"&Administration!B13","v":"     "},null,null,null,null,null,null,null,null,null,null,null,true,9]
["3. OWNER INFORMATION",null,null,null,null,null,null,null,null,null,null,null,null,null,false,13]
["   Owner's Name:",null,{"$f":"Administration!C129","v":0},null,null,null,null,null,null,null,null,null,null,null,false,14]
["   Owner's Address:",null,{"$f":"Administration!D130&\" \"&Administration!D131&\" \"&Administration!H131&\" \"&Administration!J131","v":"0 0 0 0"},null,null,null,null,null,null,null,null,null,null,null,false,15]
["   Owner's Home/Business Phone:",null,null,{"$f":"Administration!D133","v":0},null,null,null,null,null,null,null,null,null,null,false,16]
["   Owner's Business FAX:",null,null,{"$f":"Administration!D134","v":0},null,null,null,null,null,null,null,null,null,null,false,17]
["   Owner's E-Mail:",null,{"$f":"Administration!D135","v":0},null,null,null,null,null,null,null,null,null,null,null,false,18]
["   Owner's State of CT Supplier ID:",null,null,{"$f":"Administration!D136","v":0},null,null,null,null,null,null,null,null,null,null,false,19]
["   Owner's Type of Business (Check Only One):",null,null,null,null,null,null,null,null,null,null,null,null,null,false,20]
[null,"  Corporation","LLC Corporation",null,null,"LLC Partnership",null,null,null,null,"LLC Single Member Entity",null,null,null,false,21]
[null,"Non-Profit","Partnership",null,null,null,null,"        Individual/Sole Proprietor",null,null,null,null,null,null,false,22]
["4. HAP CONTRACT INFORMATION",null,null,null,null,null,null,null,null,null,null,null,null,null,false,23]
["   Tenant's Payment:        ",null,{"$f":"Administration!D146","v":0},null,null,null,null,null,null,null,null,null,null,null,false,24]
["   Housing Assistance:     ",null,{"$f":"Administration!D147","v":0},null,null,null,null,null,null,null,null,null,null,null,false,25]
["   Contract Rent:              ",null,{"$f":"Administration!D148","v":0},null,null,null,null,null,null,null,null,null,null,null,false,25]
["   Security Deposit:         ",null,{"$f":"Administration!D149","v":0},null,null,"New",null,"      Previously Paid",null,null,null,{"$f":"Administration!K151","v":0},null,null,false,26]
["   Effective Dates of HAP Contract:    ",null,null,"From:",{"$f":"Administration!F152","v":"00:00:00"},null,null,"To:",{"$f":"Administration!H152","v":"00:00:00"},null,"No. of Months:  "]
[]
["5. PAYMENT STANDARD COMPLIANCE"]
[" Check Applicable"]
[null,"*a.","     Gross rent does not exceed Grant FMR and meets Rent Reasonableness Standards"]
[null,"*b.","     Gross rent exceeds Grant FMR but meets Rent Reasonableness Standards"]
[]
["(*By checking b, the local CoC Rental Assistance housing provider verifies that sufficient funds will be available to fulfill the original"]
["grant award obligation with grant award funds.)"]
["6. COMMENTS:",null,{"$f":"Administration!C160","v":0}]
[{"$f":"Administration!B164","v":0}]
[]
[]
[]
["Submitted By:",null,{"$f":"Administration!C166","v":0},null,null,null,null,null,null,null,{"$f":"Administration!G166","v":"00:00:00"}]
[null,null,"Name",null,null,null,null,null,null,null,"Date"]
["Reviewed By:",null,{"$f":"Administration!C168","v":0},null,null,null,null,null,null,null,{"$f":"Administration!G168","v":"00:00:00"}]
[null,null,"Name",null,null,null,null,null,null,null,"Date"]
["Approved By:",null," "]
[null,null,"Name",null,null,null,null,null,null,null,"Date"]
["Last edited"]
[{"$f":"LARGE(Sheet2!C149:P167,1)","v":"2024-04-01T12:48:16"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"HAP Contract","index":6,"n_rows":313,"n_cols":12,"rows_kept":313,"cut":false,"hidden":false,"merged":[[311,0,311,2],[281,1,283,3],[9,6,10,10],[23,3,23,9],[0,6,0,7],[34,1,34,2],[20,1,20,2],[172,2,172,3],[60,1,60,2],[3,1,3,10],[52,3,52,4],[0,8,0,10],[20,3,20,7],[21,3,21,6],[137,1,137,10],[41,8,41,9],[305,1,305,3],[300,5,300,10],[215,3,215,4],[304,7,304,9],[293,1,293,3],[300,1,300,3],[287,1,287,2],[304,1,304,3],[299,1,299,3],[284,1,284,3],[288,1,288,3],[290,7,290,10],[288,6,288,9],[293,6,293,9],[136,8,136,10],[136,5,136,6],[281,6,283,9],[284,6,284,9],[287,6,287,9]]}
[null,null,null,null,null,null," Contract Number  ",null,{"$f":"Administration!C117","v":0}]
["                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                       "]
[]
[null," HOUSING ASSISTANCE PAYMENTS CONTRACT"]
["                                            For CONTINUUM OF CARE RENTAL ASSISTANCE (TRA)"]
[]
[null,"This Housing Assistance Payments Contract (Contract) is made and entered into by and between the"]
[null,"State of Connecticut (hereinafter the “STATE”) acting by its Commissioner of Mental Health and Addiction"]
[null,"Services (hereinafter the “Commissioner”) as authorized by sections 4-8, 17a-451 and 17a-450(c)(1) of the"]
[null,"General Statutes of Connecticut, and ",null,null,null,null,{"$f":"Administration!C129","v":0}]
[null,"(hereinafter the “Owner”)."]
[]
[null,"The purpose of this Contract is to assist the Family identified in section 1 (A) to lease a decent, safe, and "]
[null,"sanitary dwelling unit from the Owner.  The STATE shall make housing assistance payments to the "]
[null,"Owner in behalf of the Family in accordance with this Contract."]
[]
["1.","CONTRACT UNIT, FAMILY, AND LEASE"]
[null,"(A)","This Contract applies only to the Family and the dwelling unit (Contract unit) "]
[null,null,"designated in this section."]
[]
[null,"Contract unit:",null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10","v":"  "}]
[null,null,null,{"$f":"Administration!E125&\" \"&Administration!G125&\" \"&Administration!I125","v":"0 0 0"}]
[]
[null,"   Family:            ",null,{"$f":"Administration!C123","v":0}]
[]
[null,"    (B)","The Owner shall lease the Contract unit to the Family.  The Lease to be executed "]
[null,null,"by the Family and the"]
[null,"Owner for the Contract unit has been approved by the Connecticut Department of Mental Health and "]
[null,"Addiction Services, (DMHAS), and shall be executed in the approved form.  The Lease shall"]
[null,"contain all provisions required by the U.S. Department of Housing and Urban Development "]
[null,"(HUD), and shall not contain any provisions prohibited by HUD."]
[]
["2.","TERM OF CONTRACT"]
[null,"The term of this Contract shall begin on                    The term of this Contract shall end on             ",null,null,null,null,{"$f":"Administration!F181","v":"00:00:00"},". The term of this Contract shall end on"]
[null,{"$f":"Administration!F182","v":"00:00:00"},null,". The contract shall end in any event upon termination of the "]
[null,"CONTINUUM OF CARE RENTAL ASSISTANCE funds.",null,null,null,null,null,null,null,null,null,{"$f":"A1&\".\"","v":"."}]
[]
[]
["3.","HOUSING ASSISTANCE PAYMENTS"]
[null,"(A) ","The total monthly rent payable to the Owner during the term of this Contract is "]
[null,"called the “Contract rent.”  Initially, and until adjustment of the Contract rent in accordance with"]
[null,"this section 7 of this Contract, the Contract rent shall be      ",null,null,null,null,null,null,{"$f":"Administration!D148","v":0}]
[]
[]
[null,"B)","The portion of the Contract rent payable by the Family (“Tenant rent”) will be an "]
[null,"amount determined by the Department of Mental Health and Addiction Services, in"]
[null,"accordance with HUD regulations and requirements.  This amount is the maximum amount"]
[null,"the Owner can require the Family to pay for rent of the contract rent, including all services, "]
[null,"maintenance and utilities to be provided by the Owner in accordance with the Lease.   "]
[null,"The amount of the Tenant rent is subject to change during the term of the Contract.  "]
[null,"Any changes in the amount of the tenant rent will be effective on the date stated in a"]
[null,"notification by DMHAS to the Family and the Owner.  Initially, and until such change,"]
[null,"Family shall pay  ",null,{"$f":"Administration!D146","v":0},null,"to the Owner as the Tenant rent."]
[]
[null,"(C)","Each month DMHAS shall make a housing assistance payment to the Owner in behalf "]
[null,"of the Family in accordance with this Contract. The monthly housing assistance payment is equal"]
[null,"to the difference between the Contract rent and the Tenant rent.  The amount of the housing"]
[null,"assistance shall be determined by DMHAS.  Any change in the amount of the housing assistance"]
[null,"payment shall be effective as of the date stated in a notification by DMHAS to the Family and the "]
[null,"Owner.  Initially and until such change the amount of the housing assistance payment shall be"]
[null,{"$f":"Administration!D147","v":0},null,"per month.  DMHAS does not assume any obligation for the Tenant rent, or for "]
[null,"payment of any claim by the Owner against the Family, except in accordance with section 5.  The "]
[null,"obligation of DMHAS is limited to making housing assistance payments in behalf of the Family in "]
[null,"accordance with this Contract."]
[]
[null,"(D)","DMHAS may terminate housing assistance payments under this Contract, because of action"]
[null,"or inaction by the Family, in the following cases: (1) if the Family has committed any fraud in"]
[null,"connection with any federal housing assistance program, (2) if the Family has violated any of the"]
[null,"Family's obligations under the CONTINUUM OF CARE RENTAL ASSISTANCE Rental Assistance "]
[null,"Program, or (3) if the Family has breached an agreement with DMHAS.  DMHAS shall notify the"]
[null,"Owner in writing of its decision to terminate housing assistance payments in such case, and that housing "]
[null,"assistance payments pursuant to the Contract shall terminate at the end of the calendar month which follows "]
[null,"the calendar month in which DMHAS gives such notice to the Owner. (For provisions on"]
[null,"termination of housing assistance payments, and other remedies, because of Owner’s breach of the "]
[null,"Contract, see section 12)."]
[]
["4.","MAINTENANCE, OPERATION AND INSPECTION"]
[null,"(A)","The Owner agrees to maintain and operate the Contract unit and related facilities to provide "]
[null,"decent, safe and sanitary housing in accordance with 24 CFR Section 882.109, including the provision "]
[null,"of all the services maintenance and utilities as agreed to in the Lease. If DMHAS determines that the "]
[null,"Owner is not meeting this obligation, DMHAS shall have the right, even if the Family continues in "]
[null,"occupancy, to terminate or reduce housing assistance payments to the Owner, and to terminate the"]
[null,"Contract."]
[]
[null,"(B)","DMHAS shall have the right to inspect the Contract unit and related facilities at least annually"]
[null,"and at such other times as may be necessary, in the determination of DMHAS, to ensure that the unit is"]
[null,"in decent, safe and sanitary condition, and that the Owner is providing all the services, maintenance and "]
[null,"utilities agreed to under the Lease."]
[]
[null,"(C)","If DMHAS determines that the Contract unit is not in decent, safe and sanitary condition"]
[null,"because of an increase in Family size, or a change in Family composition, or that the Family is residing "]
[null,"in a unit larger than appropriate because of a reduction in Family size or change in Family composition,"]
[null,"DMHAS may terminate the Contract upon notice by DMHAS to the Owner."]
[]
[null,"(D)","Maintenance and replacement (including redecoration) shall be in accordance with the "]
[null,"standard practice for the building concerned as established by the Owner. "]
[]
["5.","MONTHLY PAYMENT TO THE OWNER"]
[null,"(A) ","The Owner shall be paid under this Contract on or about the first day of the month for which "]
[null,null,"payment is due.  The Owner agrees that the endorsement on the check:"]
[]
[null,null,"(1)","shall be conclusive evidence that the Owner has received the full amount of the "]
[null,null,"               housing assistance payment for the month, and "]
[]
[null,null,"(2)","shall be a certification by the Owner that:"]
[]
[null,null,null,"(a)","the Contract unit is in decent, safe, and sanitary condition and the Owner"]
[null,null,null,null,"is providing all the services, maintenance and utilities as agreed to in the"]
[null,null,null,null,"Lease,"]
[]
[null,null,null,"(b)","the Contract unit is leased to the Family named in section 1(A), and the"]
[null,null,null,null,"Lease is in accordance with section 1(B),"]
[]
[null,null,null,"(c)","the Contract rent does not materially exceed rents charged by the Owner "]
[null,null,null,null,"for other comparable unassisted units,"]
[]
[null,null,null,"(d)","except for the housing assistance payment and the Tenant rent as provided "]
[null,null,null,null,"under this Contract, the Owner has not received and will not receive any "]
[null,null,null,null,"payments or other consideration (from the Family, DMHAS, or any other "]
[null,null,null,null,"public or private source) as the rent for the Contract unit,"]
[]
[null,null,null,"(e)","the Family and/or DMHAS do not own, or have any interest in the"]
[null,null,null,null,"Contract unit. If the Owner is a cooperative, the Family may be a member"]
[null,null,null,null,"of the cooperative, and"]
[]
[null,null,null,"(f)","to the best of the Owner’s knowledge, the members of the Family occupy "]
[null,null,null,null,"the Contract unit, and the unit is used solely for the residence by the"]
[null,null,null,null,"Family, and as the Family's principal place of residence."]
[]
[null,null,null,"(g)","if the Family vacates the unit before the expiration of the occupancy"]
[null,null,null,null,"agreement, the assistance for the unit may continue for a maximum of 30 days"]
[null,null,null,null,"from the end of the month in which the unit was vacated, unless occupied "]
[null,null,null,null,"by an eligible person. No additional assistance will be paid until the unit "]
[null,null,null,null,"is occupied by another eligible person"]
[]
["6.","SECURITY DEPOSIT",null,null,null,null," "]
["(A)","The amount of the security deposit ",null,null,null,{"$f":"Administration!D188","v":0},null,"paid by",{"$f":"Administration!D190","v":0}]
[]
[]
["(B)","After the Family moves from the Contract unit, the Owner may (subject to State and local law) "]
[null,"use the security deposit, including any interest on the deposit, as reimbursement for any unpaid Tenant "]
[null,"rent or other amounts which the Family owes under the Lease.  The Owner will give the Family a "]
[null,"written list of all items charged against the security deposit and the amount of each item.  After "]
[null,"deducting the amount used as reimbursement to the Owner, the Owner shall promptly refund the full "]
[null,"amount of the balance to the Family."]
[]
["(C)","If the security deposit was paid by DMHAS, after the Family moves from the Contract unit, the "]
[null,"Owner may use the deposit (subject to State and Local Law), including any interest on the deposit, as "]
[null,"reimbursement for any unpaid tenant rent or other amounts which the Family owes under the Lease.  "]
[null,"The Owner will give the Family and the DMHAS a written list of all items charged against the security"]
[null,"deposit and the amount of each item.  After deducting the amount used as reimbursement to the Owner, "]
[null,"the Owner shall promptly refund the full amount of the balance to:  DMHAS / FSB, PO Box 1240, "]
[null,"Middletown, CT 06457. Please include the contract number in the memo section of the check."]
[]
["7.","RENT ADJUSTMENTS"]
[null,"(A) If the Contract unit is in decent, safe and sanitary condition and the Owner is otherwise in "]
[null,"compliance with the terms of the Lease and this Contract, the Contract rent shall be adjusted as follows:"]
[]
[null,null,"(1)","The Contract rent shall be adjusted as of any annual anniversary date of the Contract "]
[null,null,null,"using the applicable Section 8 Annual Adjustment Factor most recently published by "]
[null,null,null,"HUD in the Federal Register.  The contract rent may be adjusted upward or downward."]
[null,null,null,"However, in no case shall the adjusted rent be less than the Contract rent on the original "]
[null,null,null,"effective date of this Contract."]
[]
[null,"(B) Adjustments as provided in paragraph (A) of this section shall not result in material difference"]
[null,"between the rents charged for assisted and comparable unassisted units as determined by DMHAS in "]
[null,"accordance with HUD requirements."]
[]
["8.","TERMINATION OF TENANCY"]
[null,"(A)","The Owner shall not terminate the tenancy of the Family except for:"]
[]
[null,null,"(1)","Serious or repeated violation of the terms and conditions of the"]
[null,null,"           Lease;"]
[null,null,"(2)","Violation of Federal, State or local law which imposes obligations on the Family"]
[null,null,null,"In connection with the occupancy and the use of the dwelling unit and surrounding "]
[null,null,null,"premises; or"]
[null,null,"(3)","Other good cause.  The following are some example of “other good cause”: "]
[null,null,null,"nonpayment of rent, refusal to agree to a fair and equitable rent increase, material "]
[null,null,null,"noncompliance with State and local health and safety codes, or bona fide intention "]
[null,null,null,"by the Landlord to use such dwelling unit as his principal residence."]
[]
[null,"(B)","The Owner may evict the Family from the Contract unit only by instituting a court action.  The "]
[null,"Owner must notify DMHAS in writing of the commencement of procedures for termination of tenancy, "]
[null,"at the same time that the Owner gives notice to the Family under State or local law.  The notice to "]
[null,"DMHAS may be given by furnishing to DMHAS a copy of the notice to the Family. "]
[]
["9.","NONDISCRIMINATION IN HOUSING"]
[null,"(A)","The Owner shall not, in the provision of services, or in any other manner, discriminate against"]
[null,"any person on the ground of age, race, color, creed, religion, sex, familial status, handicap or national "]
[null,"origin.  Unwed parents, families with children born out of wedlock, and recipients of public assistance "]
[null,"shall not be excluded from participation in, or be denied the benefits of, the CONTINUUM OF CARE"]
[null,"RENTAL ASSISTANCE Rental Assistance Program because of such status."]
[]
[null,"(B)","The Owner shall comply with all requirements imposed by Title VIII of the Civil Rights Act of"]
[null,"1968, and any related rules and regulations."]
[]
["10.","COOPERATION IN EQUAL OPPORTUNITY COMPLIANCE REVIEWS"]
[null,"The Owner shall cooperate with DMHAS in conducting compliance reviews and complaint "]
[null,"investigations pursuant to all applicable Federal and State civil rights statues, Executive Orders, and all "]
[null,"related Federal and State laws, rules and regulations."]
[]
["11.","DMHAS ACCESS TO PREMISES AND OWNER’S RECORDS"]
[null,"(A)","The Owner shall provide any information pertinent to this Contract which "]
[null,"DMHAS may reasonably require."]
[]
[null,"(B)","The Owner shall permit DMHAS or any of its authorized representatives to have access to the"]
[null,"premises and, for the purpose of audit and examination, to have access to any books, documents, papers "]
[null,"and records of the Owner to the extent necessary to determine compliance with this Contract only, "]
[null,"including the verification of information pertinent to the housing assistance payments."]
[]
["12.","RIGHTS OF DMHAS IF OWNER BREACHES THE CONTRACT"]
[null,"(A)","Any of the following shall constitute a breach of the Contract:"]
[]
[null,null,"(1)","If the Owner has violated any obligation under this Contract; or"]
[null,null,"(2)","If the Owner has demonstrated any intention to violate any obligation under this "]
[null,null,null,"Contract;"]
[null,null,"(3)","If the Owner has committed any fraud or made any false statement to DMHAS in "]
[null,null,null,"connection with the Contract."]
[]
[null,"(B)","If DMHAS determines that a breach has occurred, DMHAS may exercise any of its rights or "]
[null,"remedies under the Contract.  DMHAS shall notify the Owner in writing of such determination, "]
[null,"including a brief statement of the reasons for determination.   The notice by DMHAS to the Owner may"]
[null,"require the Owner to take corrective action (as verified by DMHAS) by a time prescribed in the notice.  "]
[null,"DMHAS’ rights and remedies under the Contract include recovery of overpayments, termination or "]
[null,"reduction of housing assistance payments, and termination of the Contract."]
[]
[null,"(C)","Any termination or reduction of housing assistance payments, or termination of the Contract, "]
[null,"shall be effective as provided in a written notice by DMHAS to the Owner."]
[]
[null,"(D)","DMHAS’ exercise or non-exercise of any remedy for Owner breach of this Contract shall not "]
[null,"constitute a waiver of the right to exercise that or any other right or remedy at any time. "]
[]
[]
["13.","AGENT RELATION TO THIRD PARTIES"]
[null,"(A)","DMHAS does not assume any responsibility for, or liability to, any person injured as a result"]
[null,"of the Owner’s action or failure to assist in connection with the implementation of this Contract, or as a "]
[null,"result of any other action or failure to act by the Owner."]
[]
[null,"(B)","The Owner is not the agent of DMHAS, and this CONTRACT does not create or affect any "]
[null,"relationship between DMHAS and any lender to the Owner or any supplier, employees, contractors, or "]
[null,"subcontractors used by the Owner in connection with implementation of this Contract."]
[]
[null,"(C)","Nothing in this Contract shall be construed as creating any right of the Family or other third "]
[null,"party (other than DMHAS) to enforce any provision of this Contract, or to assert any claim against "]
[null,"DMHAS, or the Owner under this Contract."]
[]
["14.","CONFLICT OF INTEREST PROVISIONS"]
[null,"No employee of DMHAS who formulates policy or influences decisions with respect to the "]
[null,"CONTINUUM OF CARE RENTAL ASSISTANCE PROGRAM"]
[null,"and no public official or member of a governing body or State or local legislator who exercises functions "]
[null,"or responsibilities with respect to the CONTINUUM OF CARE RENTAL ASSISTANCE PROGRAM"]
[null,"shall have any direct or indirect interest, during this person’s tenure or for one year"]
[null,"thereafter, in this Contract or in any proceeds or benefits arising from the "]
[null,"Contract.   This provision may be waived by DMHAS for good cause."]
[]
["15.","INTEREST OF MEMBERS OF OR DELEGATES TO CONGRESS"]
[null,"No member of or delegate to the Congress of the United States or resident commissioner shall be "]
[null,"admitted to any share or part of this Contract or to any benefits which may arise from it."]
[]
["16.","TRANSFER OF THE CONTRACT"]
[null,"The Owner has not made and will not make any transfer in any form of this Contract without the prior "]
[null,"written consent of DMHAS.  A change in ownership of the Owner, such as a stock transfer or transfer of "]
[null,"the interest of a limited partner, is not subject to the provisions of this section.   Transfer of the interest "]
[null,"of a general partner is subject to the provisions of this section.  DMHAS shall give its consent to a"]
[null,"transfer of the Contract if the transferee agrees in writing (in a form acceptable to DMHAS) to comply "]
[null,"with all the terms and conditions of this Contract.  The transferee shall give DMHAS a copy of the "]
[null,"executed agreement."]
[]
[]
["17.","CONDITIONS OF HOUSING ASSISTANCE PAYMENTS The right of the Owner to receive housing "]
[null,"payments under this Contract shall be subject to compliance with all the provisions of the Contract."]
[]
["18.","ENTIRE AGREEMENT INTERPRETATION"]
[null,"(A)","This contract contains the entire agreement between the Owner and DMHAS.  No changes in"]
[null,"this Contract shall be made except in writing signed by both the Owner and DMHAS."]
[null,"(B) The Contract shall be interpreted and implemented in accordance with HUD requirements."]
[]
["19.","WARRANTY OF LEGAL CAPACITY AND CONDITION OF UNIT"]
[null,"The Owner warrants (1) that the unit is in decent, safe, and sanitary condition as defined in 24 CFR "]
[null,"Section 882.109, and (2) that the Owner has the legal right to lease the dwelling unit covered by this "]
[null,"Contract during the Contract term."]
[null,null,null,null,null,null,{"$f":"Administration!D192","v":0}]
[]
[]
[null,"Name of Witness",null,null,null,null,"Name of Owner"]
[]
[]
[]
[null,"Signature of Witness",null,null,null,null,"Signature"]
[]
[]
[]
[]
[null,"Date",null,null,null,null,"Date"]
[]
[null,null,null,null,null,null,"         State of Connecticut"]
[null,null,null,null,null,null,"     Department of Mental Health and Addiction Services"]
[]
[]
[null,null,null,null,null,null,"BY:"]
[null,"Name of Witness",null,null,null,"                          Deputy Commissioner / Commissioner"]
[]
[]
[]
[null,null,null,null,null,null,"        Date:"," "]
[null,"Signature of Witness"]
[]
[]
[]
[]
["Last edited"]
[{"$f":"LARGE(Sheet2!C178:G185,1)","v":"2024-04-01T12:48:11"},null,null,"Approved as to form by the Attorney General’s Office"]
[{"$f":"Administration!A2","v":"Version 2.1"},null,null,null,null,null," Rev. 8.8.23"]

{"sheet":"Lease","index":7,"n_rows":344,"n_cols":50,"rows_kept":344,"cut":false,"hidden":false,"merged":[[328,2,328,21],[327,29,327,48],[328,29,328,48],[324,2,324,21],[327,2,327,21],[295,2,295,23],[317,0,317,49],[318,0,318,21],[136,0,136,48],[139,0,139,51],[145,0,145,51],[290,44,290,48],[147,0,147,52],[214,3,214,4],[218,3,218,4],[143,0,143,52],[144,0,144,51],[137,0,137,51],[321,29,323,48],[56,25,56,27],[56,37,56,39],[55,22,55,24],[62,3,65,18],[70,3,70,17],[70,20,70,42],[70,44,70,55],[71,44,71,55],[227,3,227,4],[71,3,71,15],[148,1,148,45],[71,19,71,36],[130,0,130,50],[133,0,133,18],[135,0,135,50],[106,0,106,10],[132,2,132,16],[141,0,141,53],[142,0,142,51],[138,0,138,52],[126,1,126,31],[127,0,127,31],[129,0,129,50],[148,49,148,55],[0,0,0,55],[12,3,12,53],[37,3,37,42],[9,3,9,10],[9,12,9,14],[9,16,9,22],[36,36,36,50],[15,25,15,40],[23,12,23,21],[27,17,27,26],[14,29,14,36],[4,35,4,53],[3,13,3,53],[8,25,8,53],[339,2,339,21],[336,2,336,21],[337,2,337,21],[153,47,153,48],[150,1,150,45],[151,1,151,45],[152,1,152,45],[330,2,330,21],[6,2,6,28],[15,9,15,18],[38,6,38,13],[38,3,38,5],[28,31,28,40],[55,39,55,41],[65,20,65,42],[55,3,55,13],[55,14,55,16],[43,3,44,44],[65,44,65,55],[66,3,66,15],[55,32,55,34],[56,11,56,13],[66,44,66,55],[66,19,66,36],[342,0,342,3],[153,1,153,45],[149,1,149,45],[151,47,151,48],[152,47,152,48],[149,47,149,48],[149,49,149,55],[150,47,150,48],[150,49,150,55],[151,49,151,55],[152,49,152,55],[153,49,153,55],[290,37,290,43],[320,1,323,21],[324,29,324,48],[340,2,340,21],[332,29,332,48],[333,29,333,48],[336,29,336,48],[337,29,337,48],[339,29,339,48],[340,29,340,48],[332,2,332,21],[333,2,333,21]]}
["LEASE"]
[]
["1.",null,"Parties:   The parties to this Lease are:  the Landlord, in this Lease, referred to as "]
[null,null,"“we”, “us”, or “our”, ",null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C129","v":0}]
[null,null,"and the Tenant, in this Lease, referred to as “you” and “yours”,",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C123","v":0}]
[]
["2.",null,"Property: We agree to rent the following to you:"]
[]
[null,null,"a)","an apartment (the \"apartment\") located at:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10","v":"  "}]
[null,null,null,{"$f":"Administration!E125","v":0},null,null,null,null,null,null,null,",",{"$f":"Administration!G125","v":0},null,null,",",{"$f":"Administration!I125","v":0},null,null,null,null,null,null," "]
[]
[null,null,"b)","and the following furniture and appliances:"]
[null,null,null,{"$f":"Administration!D205","v":0}]
[]
["3.",null,null,"Terms and Rent:      The term of this lease begins ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F152","v":"00:00:00"}]
[null,null,null,"and ends",null,null,null,null,null,{"$f":"Administration!H152","v":"00:00:00"},null,null,null,null,null,null,null,null,null,"(a total of ",null,null,null,null,null,{"$f":"Administration!K151","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,")","Months"]
[]
[null,null,"a)",null,"This Lease has been signed by the parties on the condition that the Connecticut "]
[null,null,null,null,"Department of Mental Health and Addiction Services (DMHAS) will promptly "]
[null,null,null,null,"execute a Housing Assistance Payments Contract (Contract) with us."]
[null,null,null,null,"Accordingly, this Lease shall not become effective unless the DMHAS has "]
[null,null,null,null,"executed such a contract by the first day of occupancy specified in the Lease."]
[]
[null,null,"b)","The total rent is ",null,null,null,null,null,null,null,null,{"$f":"Administration!D184","v":0},null,null,null,null,null,null,null,null,null,"per month, payable to us in advance on the first"]
[null,null,null,"day of each month of the term of the Lease.  Payment shall be made to our address "]
[null,null,null,"set forth in paragraph 5."]
[]
[null,null,"c)","Of the total monthly rent, ",null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D186","v":0},null,null,null,null,null,null,null,null,null,"shall be payable by DMHAS "]
[null,null,null,"as housing assistance payments on your behalf and ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D185","v":0},null,null,null,null,null,null,null,null,null,"shall be"]
[null,null,null,"payable by you.  The amounts shall be subject to change by reason of changes "]
[null,null,null,"in your family’s income, family composition, or extent of exceptional medical"]
[null,null,null,"or other unusual expenses, in accordance with HUD established schedules and "]
[null,null,null,"criteria; or by reason of adjustment by the DMHAS of any applicable "]
[null,null,null,"allowance for utilities and other services.  Any such change shall be effective "]
[null,null,null,"as of the date stated in a notification to you."]
[]
[null,null,"d)","Security Deposit:   The amount of security deposit paid by "]
[null,null,null,{"$f":"Administration!F211","v":0}]
[null,null,null,"is",null,null,{"$f":"Administration!D212","v":0},null,null,null,null,null,null,null,"(insert amount or state \"None:)"]
[]
[null,null,"e)","Use of Apartment:  You will use the apartment strictly for residential "]
[null,null,null,"purposes for yourself and your family.  You will not sublease the  "]
[null,null,null,"apartment or let anyone other than those listed below live in the apartment:"]
[null,null,null,{"$f":"Administration!D214","v":0}]
[]
[]
[]
[]
[]
[]
["4.",null,null,"Utilities:"]
[]
[null,null,null,"We will pay the utilities checked with “we” and you will pay the utilities checked "]
[null,null,null,"with “you”."]
[]
[null,null,null,"General Electricity",null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C222","v":0},null,null,null,"Range",null,null,null,{"$f":"Administration!C223","v":0},null,null,null,"Hot Water",null,null,null,null,null,{"$f":"Administration!C224","v":0},null,null,null,"Heat",null,null,{"$f":"Administration!C225","v":0}]
[null,null,null,"Cooking Fuel ",null,null,null,null,null,null,null,{"$f":"Administration!C226","v":0},null,null,null,"Refuse Removal",null,null,null,null,null,null,null,null,null,{"$f":"Administration!C227","v":0},null,null,null,"Refrigerator",null,null,null,null,null,null,null,{"$f":"Administration!C228","v":0}]
[]
["5.",null,null,"Notices:  Our notices will be in writing and will be given/sent to you at the "]
[null,null,null,"apartment; your rents and your notices, which shall be in writing, will be "]
[null,null,null,"given/sent to us at:"]
[]
[null,null,null,{"$f":"Administration!C129","v":0}]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D130&\" \"&Administration!D131&\" \"&Administration!H131&\" \"&Administration!J131","v":"0 0 0 0"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D133","v":0}]
[null,null,null,"Our Name",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"   Address",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"       ",null,null,null,"Phone"]
[]
[null,null,null,"In case of emergency, you will contact the following person:"]
[]
[null,null,null,{"$f":"Administration!A237","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E237","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!K237","v":0}]
[null,null,null,"Name",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"   Address",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"                 Phone    ",null,null,null,"Phone"]
[]
["6.",null,null,"Your Duty to Maintain the Apartment:  You will maintain the apartment in a "]
[null,null,null,"clean and neat condition and at all times comply with the provisions of the "]
[null,null,null,"Housing Quality Standards of HUD, State and Local Health and Housing Code "]
[null,null,null,"Requirements."]
[]
["7.",null,null,"Alterations:  No substantial alteration, addition, or improvements will be made by "]
[null,null,null,"you in or to the apartment without prior written consent.  Such consent will not be "]
[null,null,null,"unreasonably withheld, but may be conditioned upon your agreeing to restore the "]
[null,null,null,"apartment to its prior condition before moving out.  If you receive our permission"]
[null,null,null,"to make any changes, every item you install in the apartment will immediately be "]
[null,null,null,"our property unless otherwise agreed to in writing, but you may use them until the "]
[null,null,null,"Lease expires."]
[]
["8.",null,null,"Noises; Peace and Quiet:  You agree not to allow in your apartment any excessive "]
[null,null,null,"noise or other activity which disturbs the peace and quiet of other tenants in the "]
[null,null,null,"building.  We agree to prevent other tenants and other persons in the building or "]
[null,null,null,"common areas from similarly disturbing your peace and quiet.  We agree that we, "]
[null,null,null,"and that no one acting by or through us, will disturb your peace and quiet."]
[]
["9.",null,null,"Subleasing:  You will not assign this Lease or sublet the apartment without our "]
[null,null,null,"written consent and the written consent of the Department of Mental Health and "]
[null,null,null,"Addiction Services, or its agent.  Such consent shall not be withheld without good "]
[null,null,null,"reason.  This paragraph shall not prevent you from accommodating guests for "]
[null,null,null,"reasonable, short periods of time."]
[]
["10.",null,null,"Termination:",null,null,null,null,null,null,null,"Upon termination of this Lease, you will leave the apartment, "]
[null,null,null,"remove all personal property belonging to you, and leave the apartment as clean "]
[null,null,null,"as you found it (normal wear and tear excepted)."]
[]
[]
[]
[]
[]
["            WE AGREE TO:"]
[]
["11.",null,null,"Maintenance: We will maintain the apartment in a fit, habitable, and structurally "]
[null,null,null,"sound condition and we will otherwise comply with the provisions of Chapter "]
[null,null,null,"830 of the Connecticut General Statutes, as amended, and the Housing Quality "]
[null,null,null,"Standards which state the minimum Housing Quality Standards for participation "]
[null,null,null,"of existing apartments in the Continuum of Care Rental Assistance Program."]
[null,null,null,"A copy of the Housing Quality Standards may be found at "]
[null,null,null,"http://portal.hud.gov/hudportal/documents/huddoc?id=52580.pdf"]
[]
[null,null,null,"We will maintain the apartment and all equipment provided with it, as well as "]
[null,null,null,"common areas, facilities and equipment provided for your use and benefit, in "]
[null,null,null,"compliance with Housing Quality Standards on the basis of which this Lease was "]
[null,null,null,"approved by the DMHAS, and respond in a reasonable time to your calls for "]
[null,null,null,"services consistent with said obligation.  Where applicable (as in case of multi-"]
[null,null,null,"unit buildings), such maintenance with respect to common areas, facilities and "]
[null,null,null,"equipment shall include cleaning, maintenance of lighting and equipment, "]
[null,null,null,"maintenance of grounds, lawns and shrubs; and removal of snow and ice.  Where "]
[null,null,null,"security equipment and services are to be provided by us, they are as follows:"]
[]
[null,{"$f":"Administration!A250","v":0}]
["               (Specify, or state “No schedule”)."]
[]
["               Extermination services will be provided by us as conditions may require.  If such services "]
["               are to be provided on a scheduled basis, the schedule is as follows:"]
[]
[null,null,{"$f":"Administration!A256","v":0}]
["               (Specify, or state “No schedule”)."]
[]
["               We will not discriminate against you in the provision of services or in any other manner,"]
["               on the grounds of Age, Ancestry, Color, Criminal Conviction, Familial Status, Lawful "]
["               Source of Income, Learning Disability, Marital Status, Mental Disorder, National Origin, "]
["               Physical Disability, Race, Religion, Mental Retardation, Sex, Sexual Orientation, Use of "]
["               a Guide Dog, or on any other grounds specified by federal or state law or regulation."]
[]
["               Inspections: We may not enter the apartment before the termination date of the Lease,  "]
["               except to inspect the premises, to make repairs, or to show the apartment to prospective "]
["               tenant or purchaser.  We will contact you before such entry in order to arrange a time "]
["               which would not unreasonably disturb you.  Only in case of an emergency may entry be "]
["               made without prior consent.  If such an emergency entry is made, you will be notified."]
[]
["                Repairs: We agree to complete the repairs listed below by the following dates:"]
[null,"Repairs",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date"]
[{"$f":"IF(LEN(TRIM(B150))=0, \"\", \"1.\")","v":""},{"$f":"IF(Administration!B260<>\"\", Administration!B260, \"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(LEN(TRIM(B150))=0, \"\", \"1.\")","v":""},null,{"$f":"Administration!K260","v":"00:00:00"}]
[{"$f":"IF(LEN(TRIM(B151))=0, \"\", \"2.\")","v":""},{"$f":"IF(Administration!B261<>\"\", Administration!B261, \"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(LEN(TRIM(B151))=0, \"\", \"2.\")","v":""},null,{"$f":"Administration!K261","v":"00:00:00"}]
[{"$f":"IF(LEN(TRIM(B152))=0, \"\", \"3.\")","v":""},{"$f":"IF(Administration!B262<>\"\", Administration!B262, \"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(LEN(TRIM(B152))=0, \"\", \"3.\")","v":""},null,{"$f":"Administration!K262","v":"00:00:00"}]
[{"$f":"IF(LEN(TRIM(B153))=0, \"\", \"4.\")","v":""},{"$f":"IF(Administration!B263<>\"\", Administration!B263, \"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(LEN(TRIM(B153))=0, \"\", \"4.\")","v":""},null,{"$f":"Administration!K263","v":"00:00:00"}]
[{"$f":"IF(LEN(TRIM(B154))=0, \"\", \"5.\")","v":""},{"$f":"IF(Administration!B264<>\"\", Administration!B264, \"\")","v":""},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(LEN(TRIM(B154))=0, \"\", \"5.\")","v":""},null,{"$f":"Administration!K264","v":"00:00:00"}]
[]
[]
["12.",null,"Destruction of the Apartment:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"If the apartment is rendered uninhabitable "]
[null,null,"by fire, flood, or other natural disaster during the term of this Lease, or by "]
[null,null,"operation of law, this Lease will be terminated."]
[]
["13.",null,"Additional Provisions:",null,null,null,null,null,null,null,null,null,null,null,"If any, they are attached, dated, initialed by both "]
[null,null,"parties, and are a part of this Lease."]
[]
["14.",null,"Changes:",null,null,null,null,"No changes or additions to this Lease will be made except by "]
[null,null,"written agreement between you and us. This lease and any attachments represent "]
[null,null,"the entire agreement between you and us. "]
[]
["15.",null,"TERMINATION OF TENANCY:"]
[]
[null,null,"a.",null,null,null,"General:",null,null,null,null,null,null,null,"We may not terminate your right to occupy the apartment "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"except for the following reasons:"]
[]
[null,null,null,null,null,null,null,"i.",null,null,null,null,null,null,"Material noncompliance with the Lease."]
[]
[null,null,null,null,null,null,null,"ii.",null,null,null,null,null,null,"Material failure to carry out your obligations under the "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"State’s Landlord and Tenant Act (Chapter 830 of the "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Connecticut General Statutes)."]
[]
[null,null,null,null,null,null,null,"iii.",null,null,null,null,null,null,"Other good cause, which may include your refusal to accept "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"a modification of the Lease form approved by DMHAS."]
[]
[null,null,null,null,null,null,null,"All terminations must be in accordance with the provisions of local law "]
[null,null,null,null,null,null,null,"and the State of Connecticut’s Landlord and Tenant Act and subparagraph "]
[null,null,null,null,null,null,null,"c of this paragraph."]
[]
[null,null,"b.",null,null,null,null,"NOTICE OF GOOD CAUSE:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Your conduct cannot be considered "]
[null,null,null,null,null,null,null,"“other good cause” under paragraph 15(a) (iii) unless we have given you "]
[null,null,null,null,null,null,null,"prior notice that your conduct constitutes grounds for ending your Lease. "]
[null,null,null,null,null,null,null,"We must serve the notice in the same manner as that provided for in paragraph 5."]
[]
[]
["c.",null,"MATERIAL NONCOMPLIANCE:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"The term “material noncompliance with the "]
[null,null,"Lease” includes: "]
[]
[null,null,null,"i.",null,null,"One or more substantial violations of the Lease."]
[]
[null,null,null,"ii.",null,null,"Repeated minor violations of the Lease which disrupt the livability of the "]
[null,null,null,null,null,null,"building, adversely affect the health or safety of any persons or the right of "]
[null,null,null,null,null,null,"any tenant to the quiet enjoyment of the leased apartment and related "]
[null,null,null,null,null,null,"facilities, interfere with the management of the building or have an adverse "]
[null,null,null,null,null,null,"financial effect on the building."]
[]
[null,null,null,"iii.",null,null,"Non-payment of rent or any other financial obligation due under the Lease "]
[null,null,null,null,null,null,"(including any portion thereof) beyond any grace period permitted under "]
[null,null,null,null,null,null,"state law.  The payment of rent or any other financial obligation due under "]
[null,null,null,null,null,null,"the Lease after the due date but within the grace period permitted under "]
[null,null,null,null,null,null,"State law will constitute a minor violation."]
[]
[]
[]
[]
[]
["d.",null,null,"TERMINATION NOTICE:"]
[]
[null,null,null,"(1)","(1)",null,null,"We must give you a written notice of any proposed termination of the "]
[null,null,null,null,null,null,null,"Lease, stating the reasons and that the Lease is terminated on a certain day "]
[null,null,null,null,null,null,null,"and advising you that you have an opportunity to respond to us."]
[]
[null,null,null,"(2)","(2)",null,null,"When a termination notice is issued for “other good cause” paragraph 15 "]
[null,null,null,null,null,null,null,"(a) (iii), the notice will be effective, and it will so state, at the end of a term "]
[null,null,null,null,null,null,null,"and in accordance with the termination provisions of the Lease, but in no "]
[null,null,null,null,null,null,null,"case earlier than 30 days after you receive the notice.  Where the "]
[null,null,null,null,null,null,null,"termination notice is based on a material noncompliance with the Lease or "]
[null,null,null,null,null,null,null,"material failure to carry out the obligations under the State Landlord and "]
[null,null,null,null,null,null,null,"Tenant Act and paragraphs 15 (a) & (b) of this Lease, the time of service "]
[null,null,null,null,null,null,null,"must be in accordance with the Lease and State law."]
[]
[null,null,null,"(3)","(3)",null,null,"If any judicial action is instituted to evict you, we may not rely on any "]
[null,null,null,null,null,null,null,"reasons which are different from the reasons which we stated in the notice "]
[null,null,null,null,null,null,null,"to you.  A copy of the notice must be furnished to the Department of "]
[null,null,null,null,null,null,null,"Mental Health and Addiction Services at the same time we send the notice "]
[null,null,null,null,null,null,null,"to you."]
[]
["e.",null,null,null,null,null,null,"MODIFICATION OF THE LEASE FORM: We may, with the prior "]
[null,null,null,null,null,null,null,"approval of the Department of Mental Health and Addiction Services, "]
[null,null,null,null,null,null,null,"modify the terms and conditions of the Lease form effective at the end of "]
[null,null,null,null,null,null,null,"the first term or a following term, by serving an appropriate notice to you"]
[null,null,null,null,null,null,null,"together with the offer of a revised Lease or an addition revising the "]
[null,null,null,null,null,null,null,"existing Lease.  This notice and offer must be received by you at least 30 "]
[null,null,null,null,null,null,null,"days prior to the last day on which you have the right to terminate tenancy "]
[null,null,null,null,null,null,null,"without being bound by the modified terms and conditions.  You may "]
[null,null,null,null,null,null,null,"accept the modified terms and conditions by executing the revised Lease "]
[null,null,null,null,null,null,null,"or the revised addition which we offer you, or you may reject the modified"]
[null,null,null,null,null,null,null,"terms and conditions by giving us written notice in accordance with the "]
[null,null,null,null,null,null,null,"Lease that you intend to terminate the Lease.  Any increase in rent must in "]
[null,null,null,null,null,null,null,"all cases be governed by HUD requirements for the Continuum of Care Program."]
[]
[]
["16.",null,"Not withstanding anything to the contrary contained in the Lease, any provision, "]
[null,null,"term, condition, covenant or agreement of the Lease which falls within the "]
[null,null,"classifications below shall be inapplicable."]
[]
[]
[null,null,"(1)",null,null,null,"CONFESSION OF JUDGMENT:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Consent by the Tenant to be sued, to "]
[null,null,null,null,null,null,"admit guilt, or to accept without question any judgment favoring the "]
[null,null,null,null,null,null,"Landlord in a lawsuit brought in connection with the Lease."]
[]
[]
[]
[]
[null,null,"(2)",null,null,null,"SEIZE OR HOLD PROPERTY FOR RENT OR OTHER CHARGES:"]
[null,null,null,null,null,null,"Authorization to the Landlord to take property of the Tenant and/or hold it "]
[null,null,null,null,null,null,"until the Tenant meets any obligation which the Landlord has determined  "]
[null,null,null,null,null,null,"the Tenant has failed to perform."]
[]
[null,null,"(3)",null,null,null,"EXCULPATORY CLAUSE:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Prior agreement by the Tenant not to "]
[null,null,null,null,null,null,"hold the Landlord or its agents legally responsible for acts done "]
[null,null,null,null,null,null,"improperly or for failure to act when it was required to do so."]
[]
[null,null,"(4)",null,null,null,"WAIVER OF LEGAL NOTICE:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Agreement by the Tenant that the "]
[null,null,null,null,null,null,"Landlord need not give any notices in connection with (1) a lawsuit "]
[null,null,null,null,null,null,"against the Tenant for eviction, money damages, or other purpose, or (2) "]
[null,null,null,null,null,null,"any other action affecting the Tenant’s rights under the Lease"]
[]
[null,null,"(5)",null,null,null,"WAIVER OF LEGAL PROCEEDINGS:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Agreement by the Tenant to "]
[null,null,null,null,null,null,"allow eviction without a court determination."]
[]
[null,null,"(6)",null,null,null,"WAIVER OF JURY TRIAL:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Authorization to the Landlord's lawyer to "]
[null,null,null,null,null,null,"give up the Tenant’s rights to trial by jury."]
[]
[null,null,"(7)",null,null,null,"WAIVER OF RIGHT TO APPEAL COURT DECISION: ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Authorization to "]
[null,null,null,null,null,null,"the Landlord's lawyer to give up the Tenant’s right to appeal a decision on "]
[null,null,null,null,null,null,"the ground of judicial error or to give up the Tenant’s right to sue, to "]
[null,null,null,null,null,null,"prevent a judgment from being put into effect."]
[]
[null,null,"(8)",null,null,null,"TENANT CHARGEABLE WITH COST OF LEGAL ACTIONS "]
[null,null,null,null,null,null,"REGARDLESS OF OUTCOME OF LAWSUIT:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Agreement by the "]
[null,null,null,null,null,null,"Tenant to pay lawyer’s fees or other legal cost whenever the Landlord "]
[null,null,null,null,null,null,"decides to sue the Tenant whether or not the Tenant wins."]
[]
["17.",null,"We hereby notify you that an operative fire sprinkler system ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F267","v":0}]
[null,null,"exist at the apartment."]
[]
[null,null,"If an operative fire sprinkler system exists at the apartment in accordance "]
[null,null,"with the foregoing paragraph, its last day of maintenance and inspection was "]
[null,null,{"$f":"Administration!A272","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"."]
[]
[]
[]
[]
[null,null,"As used in this paragraph, the term \"fire sprinkler system\" means a system "]
[null,null,"of piping and appurtenances designed and installed in accordance with "]
[null,null,"generally accepted standards so that heat from a fire will automatically cause "]
[null,null,"water to be discharged over the fire area to extinguish or prevent its further "]
[null,null,"spread."]
[]
[]
[]
[]
[]
[]
["18.",null,"The parties to this Lease agree that we have disclosed to you the possible presence "]
[null,null,"of lead-based paint and/or lead-based paint hazards in the apartment, that you "]
[null,null,"have received the most current version of the Protect Your Family From Lead In "]
[null,null,"Your Home pamphlet approved by the federal Environmental Protection Agency, "]
[null,null,"and that both parties have completed a lead based paint disclosure statement."]
[]
["                     WHEREFORE, we, the undersigned, agree to this Lease, by signing two copies  (one to "]
["                      be kept by you and one by us)."]
[]
[null,{"$f":"Administration!C129","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C123","v":0}]
[]
[]
[null,null,"LANDLORD (print name) ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"TENANT (print name)"]
[]
[]
[]
[null,null,"(Signature) ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Signature) "]
[]
[]
[]
[]
[null,null,"(Date of Signature) ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Date of Signature) "]
[]
[]
[]
[null,null,"(Signature) ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Signature) "]
[]
[]
[null,null,"(Date of Signature) ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Date of Signature) "]
["Last edited"]
[{"$f":"LARGE(Sheet2!A196:L268,1)","v":"2024-04-01T12:48:13"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Occupancy Continuation Form 1","index":8,"n_rows":51,"n_cols":94,"rows_kept":51,"cut":false,"hidden":false,"merged":[[39,59,39,75],[40,59,40,75],[39,4,39,14],[40,4,40,14],[39,15,39,42],[40,15,40,42],[39,43,39,58],[40,43,40,58],[21,72,21,88],[22,12,22,37],[22,38,22,48],[22,49,22,53],[22,54,22,64],[22,65,22,71],[22,72,22,88],[21,12,21,37],[21,38,21,48],[21,49,21,53],[21,54,21,64],[21,65,21,71],[38,43,38,58],[34,59,34,75],[35,59,35,75],[36,59,36,75],[37,59,37,75],[38,59,38,75],[49,0,49,11],[12,38,15,48],[16,12,16,37],[17,12,17,37],[18,12,18,37],[19,12,19,37],[12,12,15,37],[16,38,16,48],[17,38,17,48],[18,38,18,48],[19,38,19,48],[46,12,46,88],[44,72,44,88],[44,21,44,59],[36,4,36,14],[34,15,34,42],[8,111,8,119],[9,111,9,119],[12,54,15,64],[12,49,15,53],[16,54,16,64],[16,49,16,53],[10,4,10,88],[16,65,16,71],[16,72,16,88],[12,4,15,11],[12,65,15,71],[12,72,15,88],[35,4,35,14],[24,37,24,88],[25,34,25,88],[26,4,26,88],[34,4,34,14],[35,15,35,42],[34,43,34,58],[35,43,35,58],[19,72,19,88],[20,72,20,88],[0,0,0,89],[1,0,1,89],[3,0,3,89],[5,76,5,88],[6,49,6,88],[6,23,6,42],[17,49,17,53],[18,49,18,53],[17,65,17,71],[18,65,18,71],[19,65,19,71],[20,65,20,71],[17,72,17,88],[18,72,18,88],[48,0,48,4],[20,38,20,48],[20,12,20,37],[17,54,17,64],[18,54,18,64],[37,4,37,14],[37,15,37,42],[38,4,38,14],[38,15,38,42],[36,15,36,42],[36,43,36,58],[37,43,37,58],[19,49,19,53],[20,49,20,53],[19,54,19,64],[20,54,20,64]]}
["Continuum of Care Rental Assistance Program"]
["Department of Mental Health and Addiction Services"]
[]
["OCCUPANCY CONTINUATION FORM"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date",null,null,null,null,{"$f":"Administration!L279","v":"00:00:00"}]
[null,null,null,null,"Telephone Nos.  Home",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C14","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Work",null,null,null,null,null,{"$f":"Administration!C15","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,1,true]
[null,null,null,null,"Household Status: "]
[null,null,null,null,"Is the Head of Household 62 or older?",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(DATEDIF(BC17, BY6, \"Y\") >= 62, \"yes\", \"No\")","v":"No"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,4,false]
[null,null,null,null,"FAMILY COMPOSITION",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,5,false]
[null,null,null,null,"Family Member",null,null,null,null,null,null,null,"Names of Persons to Live in Unit",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Relation to Family Head",null,null,null,null,null,null,null,null,null,null,"Sex",null,null,null,null," Date of Birth",null,null,null,null,null,null,null,null,null,null,"Student Yes/No",null,null,null,null,null,null,"Social Security #",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,6,false]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,7,false]
[]
[]
[null,null,null,null,"Head",null,null,null,null,null,null,null,{"$f":"Administration!B8","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F285","v":"Self"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G285","v":0},null,null,null,null,{"$f":"Administration!C16","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I285","v":0},null,null,null,null,null,null,{"$f":"Administration!D17","v":0}]
[null,null,null,null,2,null,null,null,null,null,null,null,{"$f":"Administration!B286","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F286","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G286","v":0},null,null,null,null,{"$f":"Administration!H286","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I286","v":0},null,null,null,null,null,null,{"$f":"Administration!K286","v":0}]
[null,null,null,null,3,null,null,null,null,null,null,null,{"$f":"Administration!B287","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F287","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G287","v":0},null,null,null,null,{"$f":"Administration!H287","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I287","v":0},null,null,null,null,null,null,{"$f":"Administration!K287","v":0}]
[null,null,null,null,4,null,null,null,null,null,null,null,{"$f":"Administration!B288","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F288","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G288","v":0},null,null,null,null,{"$f":"Administration!H288","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I288","v":0},null,null,null,null,null,null,{"$f":"Administration!K288","v":0}]
[null,null,null,null,5,null,null,null,null,null,null,null,{"$f":"Administration!B289","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F289","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G289","v":0},null,null,null,null,{"$f":"Administration!H289","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I289","v":0},null,null,null,null,null,null,{"$f":"Administration!K289","v":0}]
[null,null,null,null,6,null,null,null,null,null,null,null,{"$f":"Administration!B290","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F290","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G290","v":0},null,null,null,null,{"$f":"Administration!H290","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I290","v":0},null,null,null,null,null,null,{"$f":"Administration!K290","v":0}]
[null,null,null,null,7,null,null,null,null,null,null,null,{"$f":"Administration!B291","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F291","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!G291","v":0},null,null,null,null,{"$f":"Administration!H291","v":"00:00:00"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I291","v":0},null,null,null,null,null,null,{"$f":"Administration!K291","v":0}]
[]
[null,null,null,null,"List any changes expected in household:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E293","v":0}]
[null,null,null,null,"List School(s) attended by Students:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E294","v":0}]
[null,null,null,null,{"$f":"Administration!A295","v":0}]
[]
[null,null,null,null,"GROSS INCOME AND EMPLOYMENT: List everyone who is receiving income and/or working"]
[null,null,null,null,"You must include all income from employment, tips, TANF, pension, social security, unemployment "]
[null,null,null,null,"compensation, alimony, child support, educational stipends, veterans’ benefits, SNAP, "]
[null,null,null,null,"Medicare/Medicaid and/or any other public assistance.  "]
[null,null,null,null,"Family ",null,null,null,null,null,null,null,null,null,null,"Source of Income for"]
[null,null,null,null,"Member",null,null,null,null,null,null,null,null,null,null,"All Family Members",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Amount",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Per"]
[null,null,null,null,{"$f":"Administration!A305","v":"Head"},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C305","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F305","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I305","v":0}]
[null,null,null,null,{"$f":"Administration!A306","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C306","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F306","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I306","v":0}]
[null,null,null,null,{"$f":"Administration!A307","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C307","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F307","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I307","v":0}]
[null,null,null,null,{"$f":"Administration!A308","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C308","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F308","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I308","v":0}]
[null,null,null,null,{"$f":"Administration!A309","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C309","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F309","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I309","v":0}]
[null,null,null,null,{"$f":"Administration!A310","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C310","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F310","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I310","v":0}]
[null,null,null,null,{"$f":"Administration!A311","v":0},null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C311","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F311","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!I311","v":0}]
[]
[null,null,null,null,"EMERGENCY CONTACT INFORMATION:  List person (family member, friend, sponsor, etc.) "]
[null,null,null,null,"who you would like the CoC Rental Assistance Program to contact in case of any emergencies."]
[null,null,null,null,"Emergency Contact:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C315","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Telephone #",null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!L315","v":0}]
[]
[null,null,null,null,"Address: ",null,null,null,null,null,null,null,{"$f":"Administration!B317","v":0}]
[]
["Last edited"]
[{"$f":"LARGE(Sheet2!A276:L316,1)","v":"2024-04-01T12:48:14"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Occupancy Continuation Form 2","index":9,"n_rows":51,"n_cols":81,"rows_kept":51,"cut":false,"hidden":false,"merged":[[49,0,49,12],[48,0,48,6],[34,14,34,56],[26,14,26,56],[43,12,43,35],[43,40,43,46],[16,42,16,54],[21,24,21,56],[25,14,25,56],[29,15,29,56],[33,14,33,56],[13,14,13,54],[14,14,14,54],[7,7,7,26],[8,7,8,26],[9,7,9,26],[7,27,7,35],[8,27,8,35],[9,27,9,35],[7,36,7,47],[8,36,8,47],[9,36,9,47]]}
["ASSETS"]
[]
["List all checking and savings accounts (including IRAs, Keogh accounts, and Certificate of Deposit). List the "]
["value of all stocks, bonds, trusts, pensions, or other assets owned by any household member."]
[]
["Family",null,null,null,null,null,null,"Bank Name ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Type of "]
["Member",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Account",null,null,null,null,null,null,null,null,"Balance"]
["Head",null,null,null,null,null,null,{"$f":"Administration!C327","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F327","v":0},null,null,null,null,null,null,null,null,{"$f":"Administration!H327","v":0}]
[2,null,null,null,null,null,null,{"$f":"Administration!C328","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F328","v":0},null,null,null,null,null,null,null,null,{"$f":"Administration!H328","v":0}]
[3,null,null,null,null,null,null,{"$f":"Administration!C329","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F329","v":0},null,null,null,null,null,null,null,null,{"$f":"Administration!H329","v":0}]
[null,"Yes",null,null,null,null,null,null,"No",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,11]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Do you have expenses for child care of a child aged 12 or younger?",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"If yes, provide the name, address and telephone number of the care provider:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,13]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C333","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,14]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C334","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,15]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,16]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"What is the weekly cost to you of the child care? ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"$",{"$f":"Administration!G336","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false,17]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,true,18]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Do you pay a care attendant or for any equipment for any handicapped or "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"disabled family member(s) necessary to permit that person or someone \telse in "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"the household to work? If so, what is the cost to you for the care attendant and/or "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"the equipment?  $",null,null,null,null,null,null,null,null,null,{"$f":"Administration!E341","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Do you have outstanding medical bills which you are paying? If yes list "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"them below."]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C345","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C346","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"What medical expenses do you expect to incur in the next twelve months?"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"$",{"$f":"Administration!C349","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Do you have a conservator (of person or finances)?  If so please provide the "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"name, address and type of conservator:"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C354","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C355","v":0}]
[]
[]
[null,"APPLICANT CERTIFICATION"]
[null,"I certify that the information given to the Department of Mental Health and Addiction Services on household "]
[null,"composition, income, net family assets, and allowances and deductions is accurate and complete to the best of "]
[null,"my knowledge and belief. I understand that false statements or information are grounds for termination of "]
[null,"housing assistance and termination of tenancy."]
[]
[null,"Signature of Head:",null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C358","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date:",null,null,null,{"$f":"IF(Administration!C360<>\"\", Administration!C360, \"\")","v":""}]
[]
[]
[]
[]
["Last Edited"]
[{"$f":"LARGE(Sheet2!C318:H364,1)","v":"2024-04-01T12:48:14"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Payment Notification Approval","index":10,"n_rows":47,"n_cols":63,"rows_kept":47,"cut":false,"hidden":false,"merged":[[1,103,1,109],[33,0,33,31],[4,0,4,9],[21,9,21,15],[21,23,21,29],[21,33,21,39],[10,0,10,65],[20,0,20,60],[6,0,6,36],[7,0,7,36],[8,0,8,36],[45,0,45,10],[12,0,12,53],[14,0,14,2],[12,97,12,102],[44,0,44,6],[21,58,21,62],[14,3,14,52],[36,4,36,39],[37,4,37,39],[30,0,30,10]]}
[]
[]
[]
[]
[{"$f":"IF(Administration!B367<>\"\", Administration!B367, \"\")","v":""}]
[]
[{"$f":"Administration!C123","v":0}]
[{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10","v":"  "}]
[{"$f":"Administration!E125&\" \"&Administration!G125&\" \"&Administration!I125","v":"0 0 0"}]
[]
["COC Rental Assistance Program Approval"]
[]
[]
[]
["Dear",null,null,{"$f":"Administration!D373","v":"0,"}]
[]
["I am pleased to inform you that you have been approved for the CoC Rental Assistance Program"]
["in the dwelling unit leased by you.  "]
[]
["The Monthly Contract Rent for the unit rented from:"]
[{"$f":"Administration!C129","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,",","for the"]
["term beginning",null,null,null,null,null,null,null,null,{"$f":"Administration!F152","v":"00:00:00"},null,null,null,null,null,null,"and ending",null,null,null,null,null,null,{"$f":"Administration!H152","v":"00:00:00"},null,null,null,null,null,null,null,"is",null,{"$f":"Administration!D148","v":0},null,null,null,null,null,null,"and your tenant portion is ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D146","v":0}]
["This is 30% of your yearly adjusted income.  "]
[]
["You will be receiving the executed lease for your records shortly.  If you have any questions, please "]
["call me at telephone number: ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E384","v":0}]
[]
["Please report (Within 10 days) any changes in family composition and/or income changes of more "]
["than $40 per month.  (Income change should be expected to be ongoing)."]
[]
["Sincerely,"]
[]
[{"$f":"Administration!E382","v":0}]
[{"$f":"Administration!E383","v":0}]
[]
["PC:"]
[null,null,null,null,{"$f":"Administration!B386","v":0}]
[null,null,null,null,{"$f":"Administration!B387","v":0}]
[]
[]
[]
[]
[]
[]
["Last edited"]
[{"$f":"LARGE(Sheet2!A368:G390,1)","v":"2024-04-01T12:48:14"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Rent Reasonableness","index":11,"n_rows":55,"n_cols":104,"rows_kept":55,"cut":false,"hidden":false,"merged":[[2,9,2,55],[3,19,3,56],[33,72,33,87],[32,40,32,55],[30,56,30,71],[31,56,31,71],[32,56,32,71],[30,72,30,87],[31,72,31,87],[32,72,32,87],[33,40,33,55],[33,56,33,71],[14,56,17,71],[14,72,17,87],[32,24,32,39],[30,24,30,39],[29,56,29,71],[27,56,27,71],[26,40,26,55],[27,24,27,39],[26,56,26,71],[39,54,39,71],[30,40,30,55],[39,34,39,48],[20,2,20,23],[22,2,22,23],[24,2,24,23],[31,24,31,39],[31,40,31,55],[28,24,28,39],[18,56,24,71],[18,40,24,55],[18,24,24,39],[25,24,25,39],[25,40,25,55],[25,56,25,71],[28,56,28,71],[13,2,13,23],[18,2,18,23],[13,24,13,39],[11,2,12,23],[39,11,39,21],[11,40,12,55],[29,40,29,55],[26,24,26,39],[29,24,29,39],[27,40,27,55],[28,40,28,55],[14,24,17,39],[11,24,12,39],[14,40,17,55],[42,64,42,74],[52,61,52,70],[49,35,49,36],[45,43,45,48],[49,41,49,42],[52,23,52,55],[5,2,8,23],[9,2,9,23],[10,2,10,23],[4,24,4,39],[5,24,8,39],[10,24,10,39],[9,24,9,39],[11,124,11,132],[2,133,2,142],[27,72,27,87],[28,72,28,87],[29,72,29,87],[25,72,25,87],[26,72,26,87],[4,72,4,87],[5,72,8,87],[9,72,9,87],[11,72,12,87],[18,72,24,87],[54,0,54,13],[0,2,0,87],[10,40,10,55],[10,56,10,71],[10,72,10,87],[13,40,13,55],[13,56,13,71],[13,72,13,87],[4,40,4,55],[5,40,8,55],[4,56,4,71],[5,56,8,71],[9,40,9,55],[9,56,9,71],[11,56,12,71],[33,24,33,39]]}
[null,null,"RENT REASONABLENESS CHECKLIST AND CERTIFICATION"]
[]
[null,null,"Name:",null,null,null,null,null,null,{"$f":"Administration!B8","v":0}]
[null,null,"Contract Number: ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C5","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Proposed Unit",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unit #1",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unit #2",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unit #3"]
[null,null,"Address",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10&\" \"&Administration!B11&\" \"&Administration!B12&\" \"&Administration!B13","v":"     "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F393","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H393","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J393","v":0}]
[]
[]
[]
[null,null,"Number of Bedrooms",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D397","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F397","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H397","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J397","v":0}]
[null,null,"Square Feet",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D398","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F398","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H398","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J398","v":0}]
[null,null,"Type of Unit/Construction",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D399","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F399","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H399","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J399","v":0}]
[]
[null,null,"Housing Condition",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D401","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F401","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H401","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J401","v":0}]
[null,null,"Location/Accessibility:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D402","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F402","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H402","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J402","v":0}]
[]
[]
[]
[null,null,"Amenities",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D408","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F408","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H408","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J408","v":0}]
[]
[null,null,"Unit:"]
[]
[null,null,"Site:"]
[]
[null,null,"Neighborhood:"]
[null,null,"Age in Years",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D416","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F416","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H416","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J416","v":0}]
[null,null,"Utilities (type)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D417","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F417","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H417","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J417","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D418","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F418","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H418","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J418","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D419","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F419","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H419","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J419","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D420","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F420","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H420","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J420","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,false]
[null,null,"Unit Rent",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D423","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F423","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H423","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J423","v":0}]
[null,null,"Utility Allowance",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D424","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F424","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H424","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J424","v":0}]
[null,null,"Gross Rent",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D425","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F425","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H425","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J425","v":0}]
[null,null,"Handicap Accessible?",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D426","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F426","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!H426","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!J426","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"CERTIFICATION:"]
[]
[null,null,null,null,null,null,null,null,null,null,null,"A.  Compliance with Payment Standard"]
[]
[null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!B432","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E432","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null," ",null,null,{"$f":"Administration!G432","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,"Proposed Contract Rent   +  Utility Allowance    =   Proposed Gross Rent"]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Approved rent does not exceed Fair Market Rent (FMR) of",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F435","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"If the proposed gross rent exceeds the FMR is it less than or equal to the gross rent of "]
[null,null,null,null,null,null,null,null,null,null,null,"each comparable unit shown above?   ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!F440","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"B.  Rent Reasonableness"]
[null,null,null,null,null,null,null,null,null,null,null,"Based upon a comparison with rents for comparable units, I have determined that the "]
[null,null,null,null,null,null,null,null,null,null,null,"proposed rent for the unit",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"is",null," ",null,null,null,"is not reasonable."]
[]
[]
[null,null,"Preparer's typed name:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C448","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date: ",null,null,null,null,{"$f":"IF(Administration!I448<>\"\", Administration!I448, \"\")","v":""}]
["Last edited",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rev. 02/26/2020"]
[{"$f":"LARGE(Sheet2!A395:J429,1)","v":"2024-04-01T12:48:15"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Notification of Annual Review","index":12,"n_rows":47,"n_cols":47,"rows_kept":47,"cut":false,"hidden":false,"merged":[[17,59,17,75],[45,0,45,13],[4,94,4,102],[4,4,4,15],[38,4,38,48],[37,4,37,48],[32,25,32,36],[6,4,6,54],[7,4,7,57],[8,4,8,50],[13,83,13,96],[29,30,29,63]]}
[]
[]
[]
[]
[null,null,null,null,{"$f":"IF(Administration!B454<>\"\", Administration!B454, \"\")","v":""}]
[]
[null,null,null,null,{"$f":"Administration!C458","v":","}]
[null,null,null,null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10","v":"  "}]
[null,null,null,null,{"$f":"Administration!B11&\"  \"&Administration!B12&\"  \"&Administration!B13","v":"    "}]
[]
[null,null,null,null,"CoC Rental Assistance Program"]
[null,null,null,null,null,null,null,null," Notice of Re-certification and Inspection"]
[]
[null,null,null,null,"Dear",null,null,null,{"$f":"Administration!C458","v":","}]
[]
[null,null,null,null,"You are currently participating in the CoC Rental Assistance Program through the State of Connecticut"]
[null,null,null,null,"Department of Mental Health and Addiction Services.  Our records show that you are due for your"]
[null,null,null,null,"annual re-certification and that your current lease expires",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(ISNUMBER(Administration!D456), TEXT(Administration!D456, \"MM/DD/YYYY\") & \".\", \"\")","v":""}]
[]
[null,null,null,null,"In order to process your annual re-certification, the CoC Rental Assistance Program is required by "]
[null,null,null,null,"Federal regulations to obtain income information from you and all adults 18 years of age and older in"]
[null,null,null,null,"your household. You must provide current income verification from all sources of income received,"]
[null,null,null,null,"including any entitlements, pension, unemployment assistance, or the four most recent pay stubs from "]
[null,null,null,null,"your employment, etc."]
[]
[null,null,null,null,"Please submit this information as soon as possible in the included postage paid, self addressed"]
[null,null,null,null,"envelope provided for your convenience."]
[]
[null,null,null,null,"In addition, an annual inspection must also be completed during this re-certification process. Your"]
[null,null,null,null,"annual inspection is scheduled for",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E467&\", \"&TEXT(Administration!E465,\"MM/DD/YYYY\")&\", \"&\"at \"&Administration!E466","v":", 01/00/1900, at "}]
[null,null,null,null,"At the time of inspection additional paperwork/forms will be completed and signed."]
[]
[null,null,null,null,"Please contact this office at",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E462","v":0},null,null,null,null,null,null,null,null,null,null,null," ","to confirm that you will be available for the inspection"]
[null,null,null,null,"date listed above or if you need to request another date and time."]
[]
[null,null,null,null,"Sincerely, "]
[]
[null,null,null,null,{"$f":"Administration!C460","v":0}]
[null,null,null,null,{"$f":"Administration!C461","v":0}]
[]
[null,null,null,null,"cc:    Case Manager"]
[null,null,null,null,null,null,null,null,"Property Manager"]
[null,null,null,null,null,null,null,null,"File"]
[]
["Last edited"]
[{"$f":"LARGE(Sheet2!A455:E459,1)","v":"2024-04-01T12:48:15"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"Contract Amendment","index":13,"n_rows":46,"n_cols":100,"rows_kept":46,"cut":false,"hidden":false,"merged":[[43,0,43,9],[44,0,44,13],[42,28,42,61],[44,37,44,57],[17,5,17,7],[37,5,37,29],[38,5,38,30],[23,5,23,29],[24,5,24,30],[26,5,26,29],[27,5,27,30],[41,28,41,61],[29,50,29,74],[30,50,30,75],[37,49,37,73],[24,50,24,75],[38,47,38,76],[26,50,26,74],[27,50,27,75],[21,50,23,74],[17,8,17,15],[16,14,16,82],[13,12,13,18],[13,19,13,41],[13,42,13,82],[17,16,17,65],[17,66,17,74],[3,108,3,116],[2,110,2,117],[2,0,2,87],[3,0,3,87],[4,0,4,87],[11,35,11,66],[12,21,12,55],[6,20,6,43],[8,106,8,114],[10,20,10,28],[10,34,10,87],[9,55,9,66]]}
[]
[]
["DEPARTMENT OF MENTAL HEALTH AND ADDICTION SERVICES"]
["CoC RENTAL ASSISTANCE PROGRAM"]
["CONTRACT AMENDMENT"]
[]
[null,null,null,null,null,"Contract Number:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C473","v":0}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Whereas, the Department of Mental Health and Addiction Services has entered "]
[null,null,null,null,null,"into a fully executed Housing Assistance Payment contract, effective     ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C475","v":""}]
[null,null,null,null,null,"and terminating on",null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C477","v":""},null,null,null,null,null,null,null,null,null,"with",null,null,null,{"$f":"Administration!C479","v":0}]
[null,null,null,null,null,"(Owner)",null,null,null,null,null,null,"to provide rental assistance for",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C481","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Tenant) "]
[null,null,null,null,null,"and family occupying",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C483","v":"     "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"and in addition, the above referenced contract "]
[null,null,null,null,null,"provides",null,null,null,null,null,null,{"$f":"Administration!D485","v":0},null,null,null,null,null,null,"in security deposit funds from",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!D487","v":0}]
[]
[null,null,null,null,null,null,null,null,null,"Whereas, by authorization of this amendment the effective contract owner is "]
[null,null,null,null,null,"changed to   ",null,null,null,null,null,null,null,null,{"$f":"Administration!C489&\" \"&Administration!C490","v":" "},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"`"]
[null,null,null,null,null,"on",null,null,{"$f":"Administration!D492","v":"00:00:00"},null,null,null,null,null,null,null,"(Date) The Housing Assistance Payment of the contract will remain ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E494","v":0}]
[null,null,null,null,null,"Whereas, all other terms and conditions of the original contract will remain the same."]
[null,null,null,null,null,null,null,null,"Therefore, we the undersigned agree to the aforementioned amendment as stated."]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C489","v":0}]
[]
[]
[null,null,null,null,null,"Name of Witness",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Name of Owner"]
[]
[]
[null,null,null,null,null,"Signature of Witness",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"(Signature)"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date of Signature"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"State of CT Department of "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mental Health and Addiction"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Services"]
[]
[]
[null,null,null,null,null,"Name of Witness",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null," Deputy Commissioner / Commissioner"]
[]
[]
[null,null,null,null,"APPROVED AS TO FORM:  "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Attorney general"]
["Last edited"]
[{"$f":"LARGE(Sheet2!A474:E490,1)","v":"2024-04-01T12:48:16"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date:"]
[{"$f":"Administration!A2","v":"Version 2.1"}]

{"sheet":"VAWA Lease Addendum","index":14,"n_rows":53,"n_cols":41,"rows_kept":53,"cut":false,"hidden":false,"merged":[[1,0,1,48],[24,21,24,26],[51,0,51,8],[0,0,0,48],[45,40,45,46],[46,40,46,46],[48,40,48,46],[49,40,49,46],[48,4,48,37],[49,4,49,37],[45,4,45,37],[46,4,46,37],[5,2,7,16],[5,36,7,48],[4,17,4,35],[4,2,4,16],[5,17,7,35]]}
["VAWA LEASE ADDENDUM"]
[]
["                        VIOLENCE AGAINST WOMEN REAUTHORIZATION ACT OF 2013"]
[]
[null,null,"TENANT",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"LANDLORD",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"UNIT NO. & ADDRESS"]
[null,null,{"$f":"Administration!B8","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!B21","v":0},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!C9&\" \"&Sheet2!J2&\" \"&Administration!B10&\" \"&Administration!B11&\" \"&Administration!B12&\" \"&Administration!B13","v":"     "}]
[]
[]
[]
[null,null,"This Lease Addendum adds the following paragraphs to the Lease between the above-referenced "]
[null,null,"Tenant and Landlord."]
[]
[null,null,{"$f":"1&\".\"","v":"1."},null,null,"Purpose of the addendum"]
[]
[null,null,"The Lease for the above referenced unit is being amended to include the provisions of the Violence"]
[null,null," Against Women Reauthorization Act of 2013 (VAWA).  "]
[]
[null,null,{"$f":"2&\".\"","v":"2."},null,null,"Conflicts with Other Provisions of the Lease"]
[]
[null,null,"In case of any conflict between the provisions of this Addendum and other sections of the Lease, "]
[null,null,"the provisions of this Addendum shall prevail."]
[]
[null,null,{"$f":"3&\".\"","v":"3."},null,null,"Effective Date; Term of the Lease Addendum"]
[]
[null,null,"The effective date of this Lease Addendum is ",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Administration!E503","v":""}]
[null,null,"This Lease Addendum shall continue to be in effect until the Lease is terminated. "]
[]
[null,null,{"$f":"4&\".\"","v":"4."},null,null,"VAWA Protections"]
[]
[null,null,"A.",null,null,"The Landlord may not consider incidents of domestic violence, dating violence, sexual assault"]
[null,null,null,null,null,"or stalking as serious or repeated violations of the lease or other “good cause” for termination"]
[null,null,null,null,null,"of assistance, tenancy or occupancy rights of the victim of abuse.  "]
[null,null,"B.",null,null,"The Landlord may not consider criminal activity directly relating to abuse, engaged in by a member of"]
[null,null,null,null,null,"a tenant’s household or any guest or other person under the tenant’s control, cause for termination "]
[null,null,null,null,null,"of assistance, tenancy, or occupancy rights if the tenant or an affiliated individual of the tenant is the "]
[null,null,null,null,null,"victim or threatened victim of that abuse."]
[null,null,"C.",null,null,"The Landlord may request in writing that the victim or an affiliated individual of the tenant certify"]
[null,null,null,null,null,"that the individual is a victim of abuse and that the tenant complete and submit documentation of"]
[null,null,null,null,null,"abuse, using the Certification of Domestic Violence, Dating Violence, Sexual Assault or Stalking "]
[null,null,null,null,null,"(Form HUD-50066 or HUD-91066), or other documentation as noted on the certification form, to "]
[null,null,null,null,null,"receive protection under the VAWA.  Failure to provide the documentation within 14 business days of "]
[null,null,null,null,null,"request, or an agreed upon extension date, may result in eviction."]
[null,null,"D.",null,null,"Any information submitted to the Landlord will be kept confidential and will not be disclosed to any "]
[null,null,null,null,null,"other individual or entity except if disclosure is consented to by the victim, is required for an eviction "]
[null,null,null,null,null,"or is otherwise required by law. "]
[]
[null,null,null,null,"Tenant (head of household)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date"]
[]
[]
[null,null,null,null,"Landlord",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date"]
["Last edited"]
[{"$f":"LARGE(Sheet2!B494:F498,1)","v":"2024-04-01T12:48:16"}]
[{"$f":"Administration!A2","v":"Version 2.1"}]